{"id":48075,"date":"2017-12-16T15:25:43","date_gmt":"2017-12-16T14:25:43","guid":{"rendered":"https:\/\/witoor.com\/web\/bike-night\/bike-night-bolzano-resia\/bolzano-resia-2017\/"},"modified":"2018-01-11T22:02:03","modified_gmt":"2018-01-11T21:02:03","slug":"bolzano-resia-2017","status":"publish","type":"page","link":"https:\/\/witoor.com\/en\/bike-night\/bike-night-suedtirol\/bolzano-resia-2017\/","title":{"rendered":"Bike Night Bolzano &#8211; Resia 2017"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row row_height_percent=&#8221;0&#8243; back_color=&#8221;color-121595&#8243; overlay_alpha=&#8221;50&#8243; equal_height=&#8221;yes&#8221; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; el_class=&#8221;bikenight-primariga&#8221;][vc_column column_width_percent=&#8221;100&#8243; style=&#8221;dark&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; medium_visibility=&#8221;yes&#8221; medium_width=&#8221;0&#8243; mobile_visibility=&#8221;yes&#8221; mobile_width=&#8221;0&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; width=&#8221;1\/3&#8243; el_class=&#8221;intestazione-bikenight&#8221;][vc_custom_heading heading_semantic=&#8221;h4&#8243; text_size=&#8221;h5&#8243; separator=&#8221;yes&#8221; sub_reduced=&#8221;yes&#8221; el_class=&#8221;bikenight-titoletto&#8221;]sabato 15<br \/>\ndomenica 16<br \/>\nluglio 2017[\/vc_custom_heading][vc_column_text]<\/p>\n<h5><span class=\"font-136260\">Bolzano &#8211; Lago di Resia (Curon)<\/span><\/h5>\n<p><em>villaggio partenza <\/em>piazza Walther<em><br \/>\napertura<\/em>\u00a0ore 18.00<br \/>\n<em>via!<\/em> ore 24.00<\/p>\n<hr class=\"separator-break\" \/>\n<p>[\/vc_column_text][\/vc_column][vc_column column_width_percent=&#8221;100&#8243; style=&#8221;dark&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; width=&#8221;1\/3&#8243;][vc_column_text]<strong>Distanza<\/strong> 110 km lungo la ciclabile via Claudia Augusta<br \/>\n<strong>Dislivello<\/strong>\u00a0+1500 m<br \/>\n<strong>Manto stradale<\/strong> Asfalto, sterrato ultimi km al lago[\/vc_column_text][vc_column_text]<strong>Partecipanti<\/strong>\u00a0153[\/vc_column_text][\/vc_column][vc_column column_width_percent=&#8221;100&#8243; position_vertical=&#8221;middle&#8221; align_horizontal=&#8221;align_center&#8221; style=&#8221;dark&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; width=&#8221;1\/3&#8243;][vc_button button_color=&#8221;color-524978&#8243; radius=&#8221;btn-square&#8221; border_animation=&#8221;btn-ripple-out&#8221; wide=&#8221;yes&#8221; hover_fx=&#8221;outlined&#8221; outline=&#8221;yes&#8221; border_width=&#8221;0&#8243; link=&#8221;url:%23foto|title:Foto||&#8221;]Foto[\/vc_button][vc_button radius=&#8221;btn-square&#8221; border_animation=&#8221;btn-ripple-out&#8221; wide=&#8221;yes&#8221; hover_fx=&#8221;outlined&#8221; outline=&#8221;yes&#8221; border_width=&#8221;0&#8243; link=&#8221;url:https%3A%2F%2Fvimeo.com%2F226084891|title:Video||&#8221;]Video[\/vc_button][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column width=&#8221;1\/1&#8243;][uncode_block id=&#8221;34256&#8243;][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;2&#8243; bottom_padding=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; desktop_visibility=&#8221;yes&#8221; medium_visibility=&#8221;yes&#8221; mobile_visibility=&#8221;yes&#8221; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column column_width_percent=&#8221;100&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; medium_visibility=&#8221;yes&#8221; medium_width=&#8221;0&#8243; mobile_visibility=&#8221;yes&#8221; mobile_width=&#8221;0&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; width=&#8221;1\/3&#8243;][vc_custom_heading separator=&#8221;yes&#8221; el_class=&#8221;bikenight-titoletto&#8221;]La passione per la bici non dorme mai![\/vc_custom_heading][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text]<strong>Bike Night \u00e8 un evento che unisce la bici, la\u00a0passione e le persone.<\/strong>\u00a0Giunta alla quarta edizione, la Bike Night Ferrara-Mare accende l\u2019estate: nel 2016 1500 persone hanno pedalato dalla citt\u00e0 lungo il Po.<\/p>\n<p><strong>La Bike Night Ferrara \u2013 Mare inaugura\u00a0l\u2019estate e le porte dei nostri sogni<\/strong>: dalla citt\u00e0 si pedala lungo l\u2019argine del Grande Fiume, percorrendo la ciclabile Destra Po fino al Delta, per poi arrivare a Lido di Volano, in riva al mare. Un\u2019esperienza unica affrontata in tanti modi diversi: in gruppo, in tandem, in monociclo, colorati o semplicemente s\u00e9 stessi, almeno per una notte.<\/p>\n<p><strong>L\u2019edizione 2017 vedr\u00e0 confermato il percorso con 100km tutti pianeggianti, tre ristori, la colazione all\u2019arrivo<\/strong>: vivi l\u2019attesa della mezzanotte insieme a noi al Villaggio Partenza! Le iscrizioni sono aperte e saranno a numero limitato: 1500 posti disponibili.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_icon position=&#8221;left&#8221; icon=&#8221;fa fa-image&#8221; icon_color=&#8221;color-197741&#8243; background_style=&#8221;fa-squared&#8221; heading_semantic=&#8221;h5&#8243; text_size=&#8221;h5&#8243; linked_title=&#8221;yes&#8221; title=&#8221;Edizione 2017 &#8211; Foto&#8221; link=&#8221;url:https%3A%2F%2Fwitoor.com%2Fbike-night%2Fbike-night-ferrara-mare%2Fferrara-mare-2017%2F|title:Foto%20Bike%20Night%202017||&#8221;][\/vc_icon][vc_icon position=&#8221;left&#8221; icon=&#8221;fa fa-video&#8221; icon_color=&#8221;color-197741&#8243; background_style=&#8221;fa-squared&#8221; heading_semantic=&#8221;h5&#8243; text_size=&#8221;h5&#8243; linked_title=&#8221;yes&#8221; title=&#8221;Edizione 2017 &#8211; Video&#8221; link=&#8221;url:https%3A%2F%2Fvimeo.com%2F222272675|title:Video%20Bike%20Night%202017||&#8221;][\/vc_icon][vc_icon position=&#8221;left&#8221; icon=&#8221;fa fa-map3&#8243; icon_color=&#8221;color-197741&#8243; background_style=&#8221;fa-squared&#8221; heading_semantic=&#8221;h5&#8243; text_size=&#8221;h5&#8243; linked_title=&#8221;yes&#8221; title=&#8221;Il percorso&#8221; link=&#8221;url:%23percorso|title:percorso%20Bike%20Night%20Ferrara%20Mare||&#8221;]Ferrara, la Destra Po, il Delta, il mare[\/vc_icon][vc_icon position=&#8221;left&#8221; icon=&#8221;fa fa-edit&#8221; icon_color=&#8221;color-197741&#8243; background_style=&#8221;fa-squared&#8221; heading_semantic=&#8221;h5&#8243; text_size=&#8221;h5&#8243; linked_title=&#8221;yes&#8221; title=&#8221;Partecipa alla Bike Night&#8221; link=&#8221;url:%23iscrizione|title:iscrizione%20Bike%20Night%20Ferrara%20Mare||&#8221;]100km in bici, 3 ristori, colazione e doccia all&#8217;arrivo, trasporto bagagli, assistenza meccanica e medica[\/vc_icon][vc_icon position=&#8221;left&#8221; icon=&#8221;fa fa-plus&#8221; icon_color=&#8221;color-197741&#8243; background_style=&#8221;fa-squared&#8221; heading_semantic=&#8221;h5&#8243; text_size=&#8221;h5&#8243; linked_title=&#8221;yes&#8221; title=&#8221;Scopri i nostri servizi&#8221; link=&#8221;url:%23servizi|title:iscrizione%20Bike%20Night%20Ferrara%20Mare||&#8221;]Noleggio bici e casco, assicurazione, parcheggio all&#8217;arrivo, navetta di rientro[\/vc_icon][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;2&#8243; bottom_padding=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; equal_height=&#8221;yes&#8221; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; row_name=&#8221;percorso&#8221;][vc_column column_width_percent=&#8221;100&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; medium_visibility=&#8221;yes&#8221; medium_width=&#8221;0&#8243; mobile_visibility=&#8221;yes&#8221; mobile_width=&#8221;0&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; width=&#8221;1\/3&#8243;][vc_custom_heading separator=&#8221;yes&#8221; el_class=&#8221;bikenight-titoletto&#8221;]Il percorso[\/vc_custom_heading][vc_column_text]<strong>Bolzano<\/strong><br \/>\npiazza Walther<br \/>\n<strong>via Claudia Augusta<\/strong><br \/>\nciclabile lungo l\u2019Adige, Merano (1\u00b0 ristoro), val Venosta (2\u00b0 ristoro a Plaus), Prato allo Stelvio (3\u00b0 ristoro), Glorenza<br \/>\n<strong>Lago di Resia<\/strong><br \/>\nArrivo al Campanile di Curon<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.openrunner.com\/elevation\/findORElevation4.php?id=4969481&amp;h=200&amp;w=580&amp;pa=0&amp;k=10&amp;c=0&amp;dummy=1435234083&amp;t=705c457386cdfbf179bb739d0c706a05ddeadffd2&amp;cache=4969481-S02-1435233830__0__600__290__.html&amp;nl=0\" alt=\"Profilo altimetrico Bike Night Bolzano-Resia\" \/>[\/vc_column_text][vc_icon position=&#8221;left&#8221; icon=&#8221;fa fa-map-marker&#8221; background_style=&#8221;fa-squared&#8221; heading_semantic=&#8221;p&#8221; text_size=&#8221;&#8221; linked_title=&#8221;yes&#8221; title=&#8221;Guarda il tracciato su Google Maps&#8221; link=&#8221;url:https%3A%2F%2Fwww.google.com%2Fmaps%2Fd%2Fviewer%3Fmid%3D1DCtMFkl5F6nO4Hq9qCMivFHXUP4%26hl%3Den%2520frameborder%253D%26usp%3Dsharing|title:percorso%20Bike%20Night|target:%20_blank|&#8221;][\/vc_icon][\/vc_column][vc_column column_width_percent=&#8221;100&#8243; expand_height=&#8221;yes&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; width=&#8221;2\/3&#8243;][vc_raw_html]JTNDZGl2JTIwaWQlM0QlMjJtYXBwYSUyMiUyMGNsYXNzJTNEJTIyYmlrZW5pZ2h0LW1hcHBhJTIyJTNFJTNDJTJGZGl2JTNFJTBBJTNDc2NyaXB0JTNFJTBBJTIwJTIwdmFyJTIwbWFwJTNCJTBBJTIwJTIwdmFyJTIwc3JjJTIwJTNEJTIwJTI3aHR0cHMlM0ElMkYlMkZ3d3cud2l0b29yLmNvbSUyRmZpbGVzJTJGdHJhY2NlJTJGYmlrZW5pZ2h0LWJ6LXRyYWNjaWEua216JTI3JTNCJTBBJTBBJTIwJTIwZnVuY3Rpb24lMjBpbml0TWFwJTI4JTI5JTIwJTdCJTBBJTIwJTIwJTIwJTIwbWFwJTIwJTNEJTIwbmV3JTIwZ29vZ2xlLm1hcHMuTWFwJTI4ZG9jdW1lbnQuZ2V0RWxlbWVudEJ5SWQlMjglMjdtYXBwYSUyNyUyOSUyQyUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMGNlbnRlciUzQSUyMG5ldyUyMGdvb2dsZS5tYXBzLkxhdExuZyUyODQ0LjQzNDA3NyUyQyUyMDEwLjkyNjc1OSUyOSUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMHpvb20lM0ElMjA5JTJDJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTJGJTJGbWFwVHlwZUlkJTNBJTIwJTI3dGVycmFpbiUyNyUwQSUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcyUzQSUyMCU1QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QmVsZW1lbnRUeXBlJTNBJTIwJTI3Z2VvbWV0cnklMjclMkMlMjBzdHlsZXJzJTNBJTIwJTVCJTdCY29sb3IlM0ElMjAlMjclMjMyNDJmM2UlMjclN0QlNUQlN0QlMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlN0JlbGVtZW50VHlwZSUzQSUyMCUyN2xhYmVscy50ZXh0LnN0cm9rZSUyNyUyQyUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyMzI0MmYzZSUyNyU3RCU1RCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QmVsZW1lbnRUeXBlJTNBJTIwJTI3bGFiZWxzLnRleHQuZmlsbCUyNyUyQyUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyMzc0Njg1NSUyNyU3RCU1RCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGZlYXR1cmVUeXBlJTNBJTIwJTI3YWRtaW5pc3RyYXRpdmUubG9jYWxpdHklMjclMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBlbGVtZW50VHlwZSUzQSUyMCUyN2xhYmVscy50ZXh0LmZpbGwlMjclMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBzdHlsZXJzJTNBJTIwJTVCJTdCY29sb3IlM0ElMjAlMjclMjNkNTk1NjMlMjclN0QlNUQlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlN0QlMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlN0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBmZWF0dXJlVHlwZSUzQSUyMCUyN3BvaSUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGVsZW1lbnRUeXBlJTNBJTIwJTI3bGFiZWxzLnRleHQuZmlsbCUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyM2Q1OTU2MyUyNyU3RCU1RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGZlYXR1cmVUeXBlJTNBJTIwJTI3cG9pLnBhcmslMjclMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBlbGVtZW50VHlwZSUzQSUyMCUyN2dlb21ldHJ5JTI3JTJDJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwc3R5bGVycyUzQSUyMCU1QiU3QmNvbG9yJTNBJTIwJTI3JTIzMjYzYzNmJTI3JTdEJTVEJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTdEJTJDJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTdCJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwZmVhdHVyZVR5cGUlM0ElMjAlMjdwb2kucGFyayUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGVsZW1lbnRUeXBlJTNBJTIwJTI3bGFiZWxzLnRleHQuZmlsbCUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyMzZiOWE3NiUyNyU3RCU1RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGZlYXR1cmVUeXBlJTNBJTIwJTI3cm9hZCUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGVsZW1lbnRUeXBlJTNBJTIwJTI3Z2VvbWV0cnklMjclMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBzdHlsZXJzJTNBJTIwJTVCJTdCY29sb3IlM0ElMjAlMjclMjMzODQxNGUlMjclN0QlNUQlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlN0QlMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlN0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBmZWF0dXJlVHlwZSUzQSUyMCUyN3JvYWQlMjclMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBlbGVtZW50VHlwZSUzQSUyMCUyN2dlb21ldHJ5LnN0cm9rZSUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyMzIxMmEzNyUyNyU3RCU1RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGZlYXR1cmVUeXBlJTNBJTIwJTI3cm9hZCUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGVsZW1lbnRUeXBlJTNBJTIwJTI3bGFiZWxzLnRleHQuZmlsbCUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyMzljYTViMyUyNyU3RCU1RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGZlYXR1cmVUeXBlJTNBJTIwJTI3cm9hZC5oaWdod2F5JTI3JTJDJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwZWxlbWVudFR5cGUlM0ElMjAlMjdnZW9tZXRyeSUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyMzc0Njg1NSUyNyU3RCU1RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGZlYXR1cmVUeXBlJTNBJTIwJTI3cm9hZC5oaWdod2F5JTI3JTJDJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwZWxlbWVudFR5cGUlM0ElMjAlMjdnZW9tZXRyeS5zdHJva2UlMjclMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBzdHlsZXJzJTNBJTIwJTVCJTdCY29sb3IlM0ElMjAlMjclMjMxZjI4MzUlMjclN0QlNUQlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlN0QlMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlN0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBmZWF0dXJlVHlwZSUzQSUyMCUyN3JvYWQuaGlnaHdheSUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGVsZW1lbnRUeXBlJTNBJTIwJTI3bGFiZWxzLnRleHQuZmlsbCUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyM2YzZDE5YyUyNyU3RCU1RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGZlYXR1cmVUeXBlJTNBJTIwJTI3dHJhbnNpdCUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGVsZW1lbnRUeXBlJTNBJTIwJTI3Z2VvbWV0cnklMjclMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBzdHlsZXJzJTNBJTIwJTVCJTdCY29sb3IlM0ElMjAlMjclMjMyZjM5NDglMjclN0QlNUQlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlN0QlMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlN0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBmZWF0dXJlVHlwZSUzQSUyMCUyN3RyYW5zaXQuc3RhdGlvbiUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGVsZW1lbnRUeXBlJTNBJTIwJTI3bGFiZWxzLnRleHQuZmlsbCUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyM2Q1OTU2MyUyNyU3RCU1RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGZlYXR1cmVUeXBlJTNBJTIwJTI3d2F0ZXIlMjclMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBlbGVtZW50VHlwZSUzQSUyMCUyN2dlb21ldHJ5JTI3JTJDJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwc3R5bGVycyUzQSUyMCU1QiU3QmNvbG9yJTNBJTIwJTI3JTIzMTcyNjNjJTI3JTdEJTVEJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTdEJTJDJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTdCJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwZmVhdHVyZVR5cGUlM0ElMjAlMjd3YXRlciUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGVsZW1lbnRUeXBlJTNBJTIwJTI3bGFiZWxzLnRleHQuZmlsbCUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyMzUxNWM2ZCUyNyU3RCU1RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGZlYXR1cmVUeXBlJTNBJTIwJTI3d2F0ZXIlMjclMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBlbGVtZW50VHlwZSUzQSUyMCUyN2xhYmVscy50ZXh0LnN0cm9rZSUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyMzE3MjYzYyUyNyU3RCU1RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU1RCUwQSUyMCUyMCUyMCUyMCU3RCUyOSUzQiUwQSUwQSUyMCUyMCUyMCUyMHZhciUyMGttbExheWVyJTIwJTNEJTIwbmV3JTIwZ29vZ2xlLm1hcHMuS21sTGF5ZXIlMjhzcmMlMkMlMjAlN0IlMEElMjAlMjAlMjAlMjAlMjAlMjBzdXBwcmVzc0luZm9XaW5kb3dzJTNBJTIwdHJ1ZSUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMHByZXNlcnZlVmlld3BvcnQlM0ElMjBmYWxzZSUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMG1hcCUzQSUyMG1hcCUwQSUyMCUyMCUyMCUyMCU3RCUyOSUzQiUwQSUyMCUyMCU3RCUwQSUzQyUyRnNjcmlwdCUzRSUwQSUzQ3NjcmlwdCUyMGFzeW5jJTIwZGVmZXIlMEFzcmMlM0QlMjJodHRwcyUzQSUyRiUyRm1hcHMuZ29vZ2xlYXBpcy5jb20lMkZtYXBzJTJGYXBpJTJGanMlM0ZrZXklM0RBSXphU3lBbGZXSElNZ0J5ZHlGZWJXWnJRVmtfWEItcTlKdXpoRjQlMjZjYWxsYmFjayUzRGluaXRNYXAlMjIlM0UlMEElM0MlMkZzY3JpcHQlM0U=[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/1&#8243;][uncode_block id=&#8221;34338&#8243;][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column width=&#8221;1\/3&#8243;][vc_custom_heading separator=&#8221;yes&#8221; el_class=&#8221;bikenight-titoletto&#8221;]Foto[\/vc_custom_heading][vc_column_text]di Mirko Merchiori e Giulia Paratelli[\/vc_column_text][\/vc_column][vc_column width=&#8221;2\/3&#8243;][vc_tabs vertical=&#8221;yes&#8221;][vc_tab title=&#8221;La festa al venerd\u00ec&#8221; tab_id=&#8221;1512639137-1-971513247018481&#8243;]<div id='gallery-1' class='gallery galleryid-48075 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-3.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-3-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-3-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-3-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-3-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-5.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-5-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-5-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-5-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-5-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-6.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-6-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-6-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-6-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-6-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-6-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-8.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-8-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-8-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-8-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-8-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-8-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-9.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-9-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-9-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-9-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-9-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-9-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-10.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-10-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-10-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-10-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-10-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-10-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-12.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-12-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-12-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-12-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-12-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-12-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-13.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-13-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-13-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-13-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-13-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-13-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-14.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-14-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-14-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-14-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-14-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-14-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-15.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-15-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-15-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-15-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-15-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-15-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-16.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-16-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-16-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-16-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-16-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-16-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-17.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-17-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-17-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-17-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-17-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-17-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-18.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-18-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-18-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-18-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-18-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-18-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-20.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-20-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-20-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-20-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-20-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-20-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-21.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-21-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-21-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-21-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-21-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-21-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-24.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-24-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-24-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-24-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-24-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-24-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-25.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-25-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-25-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-25-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-25-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-25-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-26.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-26-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-26-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-26-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-26-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-26-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-27.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-27-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-27-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-27-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-27-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-27-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-28.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-28-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-28-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-28-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-28-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-28-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-29.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-29-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-29-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-29-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-29-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-29-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-30.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-30-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-30-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-30-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-30-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-30-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-31.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-31-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-31-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-31-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-31-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-31-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-32.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-32-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-32-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-32-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-32-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-32-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-33.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-33-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-33-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-33-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-33-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-33-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-34.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-34-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-34-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-34-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-34-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-34-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-35.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-35-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-35-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-35-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-35-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-35-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-36.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-36-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-36-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-36-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-36-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-36-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-37.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-37-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-37-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-37-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-37-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-37-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-39.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-39-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-39-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-39-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-39-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-39-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-40.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-40-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-40-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-40-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-40-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-40-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-41.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-41-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-41-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-41-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-41-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-41-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-45.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-45-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-45-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-45-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-45-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-45-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-46.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-46-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-46-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-46-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-46-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-46-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-48.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-48-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-48-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-48-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-48-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-48-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-51.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-51-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-51-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-51-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-51-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-51-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-53.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-53-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-53-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-53-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-53-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-53-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-54.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-54-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-54-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-54-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-54-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-54-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-55.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-55-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-55-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-55-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-55-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-55-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-57.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-57-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-57-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-57-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-57-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-57-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-59.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-59-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-59-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-59-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-59-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-59-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-61.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-61-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-61-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-61-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-61-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-61-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-62.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-62-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-62-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-62-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-62-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-62-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-63.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-63-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-63-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-63-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-63-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-63-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-64.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-64-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-64-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-64-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-64-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-64-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-65.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-65-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-65-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-65-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-65-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-65-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n[\/vc_tab][vc_tab title=&#8221;Prima della partenza&#8221; tab_id=&#8221;1512639137-2-371513247018481&#8243;]<div id='gallery-2' class='gallery galleryid-48075 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-2.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-2-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-2-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-2-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-2-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-3.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-3-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-3-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-3-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-3-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-4.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-4-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-4-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-4-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-4-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-5.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-5-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-5-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-5-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-5-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-6.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-6-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-6-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-6-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-6-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-6-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-7.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-7-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-7-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-7-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-7-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-7-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-8.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-8-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-8-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-8-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-8-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-8-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-9.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-9-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-9-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-9-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-9-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-9-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-10.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-10-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-10-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-10-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-10-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-10-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-11.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-11-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-11-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-11-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-11-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-11-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-12.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-12-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-12-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-12-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-12-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-12-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-13.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-13-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-13-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-13-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-13-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-13-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-14.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-14-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-14-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-14-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-14-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-14-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-16.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-16-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-16-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-16-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-16-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-16-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-17.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-17-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-17-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-17-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-17-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-17-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-18.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-18-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-18-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-18-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-18-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-18-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-19.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-19-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-19-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-19-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-19-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-19-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-20.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-20-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-20-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-20-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-20-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-20-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-21.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-21-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-21-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-21-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-21-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-21-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-23.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-23-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-23-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-23-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-23-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-23-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-25.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-25-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-25-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-25-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-25-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-25-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-26.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-26-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-26-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-26-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-26-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-26-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-27.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-27-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-27-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-27-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-27-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-27-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-29.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-29-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-29-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-29-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-29-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-29-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-31.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-31-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-31-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-31-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-31-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-31-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-32.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-32-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-32-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-32-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-32-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-32-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-33.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-33-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-33-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-33-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-33-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-33-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-34.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-34-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-34-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-34-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-34-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-34-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-35.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-35-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-35-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-35-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-35-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-35-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-37.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-37-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-37-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-37-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-37-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-37-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-38.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-38-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-38-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-38-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-38-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-38-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-39.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-39-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-39-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-39-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-39-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-39-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-41.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-41-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-41-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-41-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-41-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-41-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-42.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-42-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-42-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-42-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-42-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-42-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-43.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-43-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-43-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-43-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-43-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-43-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-44.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-44-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-44-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-44-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-44-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-44-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-45.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-45-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-45-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-45-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-45-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-45-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-47.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-47-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-47-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-47-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-47-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-47-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-48.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-48-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-48-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-48-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-48-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-48-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-52.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-52-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-52-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-52-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-52-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-52-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-54.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-54-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-54-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-54-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-54-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-54-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-55.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-55-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-55-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-55-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-55-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-55-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-56.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-56-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-56-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-56-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-56-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-56-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-57.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-57-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-57-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-57-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-57-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-57-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-58.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-58-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-58-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-58-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-58-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-58-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-59.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-59-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-59-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-59-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-59-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-59-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-60.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-60-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-60-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-60-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-60-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-60-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-61.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-61-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-61-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-61-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-61-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-61-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-62.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-62-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-62-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-62-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-62-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-62-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-63.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-63-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-63-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-63-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-63-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-63-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-64.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-64-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-64-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-64-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-64-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-64-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-65.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-65-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-65-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-65-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-65-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-65-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-66.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-66-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-66-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-66-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-66-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-66-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-67.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-67-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-67-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-67-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-67-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-67-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-69.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-69-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-69-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-69-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-69-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-69-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-70.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-70-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-70-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-70-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-70-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-70-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-71.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-71-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-71-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-71-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-71-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-71-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-72.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-72-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-72-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-72-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-72-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-72-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-73.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-73-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-73-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-73-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-73-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-73-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-74.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-74-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-74-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-74-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-74-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-74-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-75.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-75-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-75-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-75-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-75-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-75-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-76.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-76-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-76-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-76-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-76-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-76-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-77.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-77-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-77-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-77-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-77-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-77-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-78.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-78-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-78-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-78-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-78-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-78-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-79.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-79-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-79-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-79-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-79-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-79-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-80.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-80-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-80-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-80-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-80-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-80-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-81.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-81-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-81-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-81-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-81-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-81-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-82.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-82-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-82-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-82-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-82-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-82-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-83.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-83-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-83-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-83-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-83-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-83-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-84.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-84-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-84-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-84-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-84-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-84-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-85.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-85-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-85-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-85-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-85-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-85-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-86.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-86-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-86-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-86-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-86-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-86-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-87.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-87-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-87-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-87-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-87-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-87-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-88.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-88-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-88-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-88-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-88-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-88-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-89.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-89-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-89-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-89-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-89-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-89-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-90.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-90-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-90-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-90-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-90-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-90-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-91.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-91-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-91-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-91-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-91-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-91-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-92.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-92-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-92-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-92-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-92-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-92-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-93.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-93-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-93-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-93-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-93-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-93-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-94.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-94-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-94-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-94-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-94-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-94-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-95.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-95-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-95-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-95-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-95-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-95-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-97.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-97-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-97-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-97-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-97-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-97-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-99.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-99-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-99-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-99-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-99-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-99-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-101.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-101-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-101-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-101-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-101-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-101-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-102.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-102-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-102-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-102-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-102-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-102-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-103.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-103-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-103-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-103-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-103-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-103-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-104.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-104-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-104-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-104-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-104-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-104-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-106.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-106-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-106-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-106-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-106-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-106-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-107.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-107-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-107-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-107-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-107-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-107-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-108.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-108-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-108-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-108-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-108-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-108-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-109.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-109-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-109-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-109-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-109-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-109-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-110.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-110-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-110-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-110-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-110-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-110-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-112.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-112-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-112-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-112-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-112-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-112-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-113.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-113-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-113-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-113-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-113-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-113-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-114.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-114-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-114-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-114-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-114-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-114-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-115.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-115-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-115-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-115-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-115-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-115-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-116.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-116-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-116-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-116-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-116-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-116-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-117.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-117-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-117-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-117-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-117-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-117-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-118.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-118-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-118-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-118-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-118-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-118-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-119.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-119-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-119-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-119-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-119-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-119-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-120.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-120-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-120-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-120-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-120-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-120-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-121.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-121-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-121-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-121-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-121-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-121-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-122.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-122-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-122-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-122-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-122-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-122-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-123.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-123-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-123-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-123-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-123-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-123-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-124.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-124-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-124-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-124-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-124-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-124-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-125.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-125-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-125-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-125-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-125-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-125-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-126.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-126-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-126-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-126-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-126-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-126-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-128.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-128-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-128-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-128-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-128-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-128-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-129.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-129-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-129-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-129-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-129-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-129-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-130.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-130-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-130-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-130-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-130-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-130-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-131.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-131-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-131-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-131-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-131-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-131-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-132.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-132-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-132-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-132-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-132-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-132-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-133.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-133-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-133-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-133-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-133-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-133-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-134.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-134-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-134-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-134-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-134-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-134-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-135.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-135-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-135-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-135-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-135-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-135-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-136.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-136-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-136-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-136-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-136-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-136-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-137.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-137-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-137-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-137-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-137-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-137-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-138.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-138-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-138-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-138-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-138-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-138-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-139.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-139-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-139-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-139-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-139-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-139-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-140.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-140-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-140-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-140-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-140-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-140-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-141.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-141-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-141-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-141-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-141-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-141-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-142.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-142-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-142-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-142-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-142-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-142-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-143.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-143-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-143-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-143-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-143-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-143-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-145.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-145-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-145-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-145-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-145-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-145-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-146.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-146-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-146-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-146-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-146-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-146-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-147.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-147-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-147-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-147-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-147-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-147-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-148.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-148-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-148-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-148-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-148-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-148-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-149.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-149-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-149-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-149-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-149-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-149-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-150.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-150-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-150-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-150-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-150-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-150-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-151.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-151-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-151-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-151-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-151-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-151-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-152.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-152-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-152-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-152-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-152-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-152-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-153.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-153-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-153-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-153-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-153-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-153-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-155.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-155-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-155-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-155-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-155-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-155-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-156.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-156-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-156-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-156-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-156-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-156-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-158.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-158-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-158-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-158-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-158-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-158-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-159.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-159-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-159-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-159-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-159-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-159-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-160.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-160-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-160-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-160-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-160-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-160-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-161.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-161-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-161-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-161-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-161-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-161-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-162.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-162-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-162-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-162-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-162-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-162-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n<div id='gallery-3' class='gallery galleryid-48075 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-3.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-3-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-3-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-3-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-3-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-5.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-5-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-5-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-5-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-5-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-6.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-6-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-6-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-6-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-6-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-6-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-8.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-8-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-8-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-8-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-8-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-8-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-9.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-9-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-9-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-9-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-9-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-9-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-10.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-10-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-10-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-10-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-10-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-10-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-12.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-12-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-12-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-12-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-12-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-12-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-13.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-13-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-13-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-13-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-13-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-13-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-14.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-14-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-14-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-14-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-14-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-14-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-15.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-15-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-15-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-15-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-15-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-15-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-16.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-16-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-16-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-16-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-16-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-16-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-17.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-17-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-17-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-17-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-17-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-17-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-18.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-18-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-18-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-18-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-18-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-18-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-20.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-20-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-20-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-20-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-20-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-20-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-21.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-21-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-21-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-21-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-21-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-21-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-24.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-24-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-24-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-24-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-24-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-24-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-25.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-25-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-25-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-25-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-25-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-25-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-26.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-26-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-26-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-26-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-26-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-26-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-27.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-27-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-27-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-27-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-27-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-27-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-28.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-28-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-28-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-28-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-28-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-28-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-29.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-29-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-29-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-29-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-29-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-29-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-30.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-30-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-30-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-30-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-30-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-30-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-31.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-31-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-31-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-31-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-31-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-31-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-32.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-32-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-32-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-32-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-32-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-32-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-33.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-33-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-33-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-33-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-33-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-33-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-34.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-34-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-34-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-34-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-34-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-34-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-35.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-35-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-35-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-35-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-35-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-35-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-36.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-36-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-36-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-36-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-36-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-36-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-37.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-37-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-37-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-37-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-37-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-37-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-39.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-39-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-39-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-39-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-39-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-39-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-40.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-40-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-40-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-40-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-40-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-40-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-41.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-41-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-41-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-41-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-41-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-41-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-45.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-45-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-45-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-45-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-45-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-45-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-46.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-46-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-46-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-46-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-46-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-46-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-48.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-48-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-48-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-48-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-48-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-48-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-51.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-51-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-51-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-51-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-51-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-51-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-53.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-53-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-53-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-53-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-53-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-53-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-54.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-54-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-54-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-54-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-54-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-54-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-55.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-55-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-55-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-55-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-55-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-55-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-57.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-57-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-57-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-57-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-57-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-57-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-59.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-59-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-59-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-59-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-59-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-59-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-61.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-61-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-61-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-61-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-61-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-61-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-62.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-62-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-62-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-62-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-62-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-62-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-63.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-63-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-63-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-63-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-63-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-63-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-64.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-64-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-64-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-64-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-64-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-64-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-65.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-65-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-65-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-65-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-65-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ritiro-pacchi-Logo-65-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n[\/vc_tab][vc_tab title=&#8221;Prima della partenza&#8221; tab_id=&#8221;1512639137-2-371513247018481&#8243;]<div id='gallery-4' class='gallery galleryid-48075 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-163.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-163-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-163-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-163-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-163-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-163-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-164.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-164-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-164-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-164-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-164-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-164-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-165.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-165-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-165-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-165-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-165-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-165-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-166.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-166-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-166-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-166-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-166-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-166-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-167.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-167-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-167-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-167-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-167-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-167-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-168.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-168-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-168-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-168-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-168-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-168-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-169.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-169-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-169-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-169-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-169-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-169-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-170.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-170-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-170-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-170-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-170-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-170-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-171.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-171-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-171-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-171-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-171-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-171-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-172.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-172-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-172-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-172-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-172-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-172-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-173.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-173-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-173-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-173-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-173-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-173-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-174.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-174-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-174-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-174-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-174-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-174-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-175.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-175-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-175-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-175-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-175-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-175-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-176.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-176-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-176-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-176-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-176-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-176-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-177.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-177-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-177-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-177-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-177-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-177-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-178.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-178-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-178-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-178-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-178-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-178-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-179.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-179-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-179-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-179-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-179-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-179-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-180.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-180-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-180-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-180-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-180-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-180-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-181.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-181-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-181-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-181-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-181-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-181-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-182.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-182-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-182-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-182-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-182-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-182-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-183.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-183-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-183-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-183-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-183-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-183-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-184.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-184-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-184-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-184-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-184-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-184-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-185.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-185-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-185-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-185-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-185-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-185-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-186.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-186-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-186-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-186-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-186-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-186-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-187.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-187-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-187-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-187-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-187-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-187-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-188.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-188-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-188-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-188-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-188-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-188-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-189.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-189-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-189-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-189-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-189-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-189-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-190.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-190-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-190-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-190-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-190-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-190-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-191.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-191-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-191-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-191-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-191-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-191-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-192.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-192-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-192-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-192-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-192-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-192-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-193.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-193-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-193-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-193-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-193-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-193-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-194.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-194-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-194-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-194-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-194-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-194-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-195.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-195-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-195-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-195-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-195-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-195-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-196.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-196-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-196-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-196-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-196-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-196-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-197.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-197-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-197-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-197-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-197-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-197-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-198.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-198-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-198-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-198-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-198-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-198-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-199.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-199-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-199-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-199-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-199-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-199-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-200.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-200-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-200-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-200-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-200-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-200-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-201.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-201-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-201-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-201-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-201-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-201-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-202.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-202-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-202-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-202-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-202-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Pre-Ride-Logo-202-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5945.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5945-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5945-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5945-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5945-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5945-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6070.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6070-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6070-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6070-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6070-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6070-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6049.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6049-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6049-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6049-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6049-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6049-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6047.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6047-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6047-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6047-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6047-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6047-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6046.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6046-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6046-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6046-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6046-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6046-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6034.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6034-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6034-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6034-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6034-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6034-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6026.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6026-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6026-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6026-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6026-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6026-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6021.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6021-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6021-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6021-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6021-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6021-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6020.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6020-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6020-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6020-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6020-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6020-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6014.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6014-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6014-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6014-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6014-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6014-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6000.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6000-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6000-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6000-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6000-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6000-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5998.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5998-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5998-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5998-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5998-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5998-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5993.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5993-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5993-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5993-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5993-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5993-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5992.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5992-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5992-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5992-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5992-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5992-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5991.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5991-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5991-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5991-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5991-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5991-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5990.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5990-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5990-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5990-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5990-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5990-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5983.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5983-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5983-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5983-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5983-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5983-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5980.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5980-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5980-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5980-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5980-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5980-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5975.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5975-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5975-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5975-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5975-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5975-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5965.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5965-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5965-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5965-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5965-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-5965-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n[\/vc_tab][vc_tab title=&#8221;Ride&#8221; tab_id=&#8221;1512639236989-2-81513247018481&#8243;]<div id='gallery-5' class='gallery galleryid-48075 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-2.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-2-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-2-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-2-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-2-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-3.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-3-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-3-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-3-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-3-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-4.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-4-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-4-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-4-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-4-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-5.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-5-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-5-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-5-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-5-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-6.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-6-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-6-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-6-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-6-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-6-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-7.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-7-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-7-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-7-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-7-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-7-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-8.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-8-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-8-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-8-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-8-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-8-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-9.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-9-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-9-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-9-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-9-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-9-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-10.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-10-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-10-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-10-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-10-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-10-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-11.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-11-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-11-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-11-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-11-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-11-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-12.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-12-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-12-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-12-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-12-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-12-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-13.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-13-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-13-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-13-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-13-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-13-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-14.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-14-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-14-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-14-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-14-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-14-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-15.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-15-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-15-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-15-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-15-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-15-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-16.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-16-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-16-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-16-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-16-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-16-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-17.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-17-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-17-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-17-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-17-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-17-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-18.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-18-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-18-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-18-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-18-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-18-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-19.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-19-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-19-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-19-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-19-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-19-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-20.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-20-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-20-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-20-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-20-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-20-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-21.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-21-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-21-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-21-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-21-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-21-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-22.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-22-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-22-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-22-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-22-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-22-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-23.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-23-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-23-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-23-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-23-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-23-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-24.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-24-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-24-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-24-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-24-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-24-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-25.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-25-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-25-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-25-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-25-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-25-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-26.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-26-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-26-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-26-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-26-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-26-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-27.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-27-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-27-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-27-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-27-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-27-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-28.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-28-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-28-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-28-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-28-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-28-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-29.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-29-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-29-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-29-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-29-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-29-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-30.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-30-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-30-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-30-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-30-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-30-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-31.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-31-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-31-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-31-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-31-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-31-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-32.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-32-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-32-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-32-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-32-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-32-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-33.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-33-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-33-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-33-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-33-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-33-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-34.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-34-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-34-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-34-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-34-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-34-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-35.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-35-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-35-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-35-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-35-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-35-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-36.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-36-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-36-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-36-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-36-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-36-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-37.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-37-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-37-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-37-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-37-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-37-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-38.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-38-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-38-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-38-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-38-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-38-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-39.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-39-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-39-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-39-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-39-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-39-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-40.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-40-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-40-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-40-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-40-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-40-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-41.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-41-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-41-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-41-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-41-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-41-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-42.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-42-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-42-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-42-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-42-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-42-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-43.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-43-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-43-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-43-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-43-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-43-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-44.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-44-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-44-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-44-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-44-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-44-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-47.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-47-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-47-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-47-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-47-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-47-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-48.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-48-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-48-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-48-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-48-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-48-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-49.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-49-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-49-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-49-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-49-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-49-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-50.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-50-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-50-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-50-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-50-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-50-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-51.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-51-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-51-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-51-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-51-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-51-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-52.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-52-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-52-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-52-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-52-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-52-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-53.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-53-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-53-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-53-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-53-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-53-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-54.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-54-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-54-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-54-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-54-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-54-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-55.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-55-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-55-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-55-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-55-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-55-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-56.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-56-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-56-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-56-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-56-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-56-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-57.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-57-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-57-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-57-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-57-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-57-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-58.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-58-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-58-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-58-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-58-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-58-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-59.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-59-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-59-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-59-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-59-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-59-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-60.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-60-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-60-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-60-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-60-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-60-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-61.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-61-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-61-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-61-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-61-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-61-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-62.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-62-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-62-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-62-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-62-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-62-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-63.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-63-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-63-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-63-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-63-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-63-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-64.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-64-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-64-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-64-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-64-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-64-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-65.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-65-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-65-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-65-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-65-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-65-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-66.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-66-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-66-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-66-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-66-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-66-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-67.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-67-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-67-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-67-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-67-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-67-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-68.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-68-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-68-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-68-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-68-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-68-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-70.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-70-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-70-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-70-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-70-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-70-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-71.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-71-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-71-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-71-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-71-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-71-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-73.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-73-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-73-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-73-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-73-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-73-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-74.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-74-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-74-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-74-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-74-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-74-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-75.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-75-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-75-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-75-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-75-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-75-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-76.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-76-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-76-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-76-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-76-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-76-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-77.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-77-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-77-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-77-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-77-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-77-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-78.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-78-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-78-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-78-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-78-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-78-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-79.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-79-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-79-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-79-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-79-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-79-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-80.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-80-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-80-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-80-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-80-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-80-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-81.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-81-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-81-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-81-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-81-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-81-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-82.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-82-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-82-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-82-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-82-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-82-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-83.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-83-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-83-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-83-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-83-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-83-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-84.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-84-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-84-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-84-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-84-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-84-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-85.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-85-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-85-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-85-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-85-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-85-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-86.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-86-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-86-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-86-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-86-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-86-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-87.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-87-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-87-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-87-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-87-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-87-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-88.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-88-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-88-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-88-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-88-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-88-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-89.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-89-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-89-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-89-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-89-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-89-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-90.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-90-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-90-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-90-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-90-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-90-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-91.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-91-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-91-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-91-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-91-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-91-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-92.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-92-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-92-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-92-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-92-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-92-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-93.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-93-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-93-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-93-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-93-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-93-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-94.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-94-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-94-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-94-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-94-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-94-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-95.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-95-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-95-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-95-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-95-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-95-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-96.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-96-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-96-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-96-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-96-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-96-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-97.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-97-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-97-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-97-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-97-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-97-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-98.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-98-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-98-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-98-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-98-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-98-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-99.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-99-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-99-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-99-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-99-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-99-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-100.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-100-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-100-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-100-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-100-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-100-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-101.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-101-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-101-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-101-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-101-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-101-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-102.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-102-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-102-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-102-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-102-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-102-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-103.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-103-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-103-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-103-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-103-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-103-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-104.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-104-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-104-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-104-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-104-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-104-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-105.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-105-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-105-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-105-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-105-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-105-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-106.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-106-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-106-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-106-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-106-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-106-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-107.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-107-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-107-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-107-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-107-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-107-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-108.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-108-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-108-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-108-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-108-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-108-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-109.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-109-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-109-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-109-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-109-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-109-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-110.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-110-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-110-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-110-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-110-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-110-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-111.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-111-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-111-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-111-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-111-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-111-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-112.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-112-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-112-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-112-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-112-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-112-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-113.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-113-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-113-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-113-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-113-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-113-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-114.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-114-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-114-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-114-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-114-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-114-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-115.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-115-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-115-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-115-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-115-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-115-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-116.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-116-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-116-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-116-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-116-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-116-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-117.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-117-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-117-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-117-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-117-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-117-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-118.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-118-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-118-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-118-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-118-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-118-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-119.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-119-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-119-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-119-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-119-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-119-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-120.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-120-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-120-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-120-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-120-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-120-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-121.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-121-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-121-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-121-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-121-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-121-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-122.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-122-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-122-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-122-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-122-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-122-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-123.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-123-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-123-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-123-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-123-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-123-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-124.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-124-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-124-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-124-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-124-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-124-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-125.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-125-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-125-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-125-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-125-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-125-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-126.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-126-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-126-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-126-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-126-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-126-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-127.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-127-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-127-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-127-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-127-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-127-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-128.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-128-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-128-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-128-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-128-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-128-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-129.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-129-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-129-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-129-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-129-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-129-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-130.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-130-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-130-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-130-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-130-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-130-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-131.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-131-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-131-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-131-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-131-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-131-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-132.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-132-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-132-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-132-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-132-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-132-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-133.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-133-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-133-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-133-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-133-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-133-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-134.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-134-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-134-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-134-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-134-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-134-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-135.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-135-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-135-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-135-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-135-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-135-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-136.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-136-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-136-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-136-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-136-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-136-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-137.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-137-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-137-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-137-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-137-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-137-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-138.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-138-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-138-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-138-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-138-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-138-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-139.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-139-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-139-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-139-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-139-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-139-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-140.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-140-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-140-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-140-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-140-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-140-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-141.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-141-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-141-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-141-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-141-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-141-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-142.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-142-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-142-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-142-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-142-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-142-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-143.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-143-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-143-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-143-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-143-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-143-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-144.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-144-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-144-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-144-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-144-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-144-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-145.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-145-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-145-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-145-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-145-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-145-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-146.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-146-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-146-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-146-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-146-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-146-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n<div id='gallery-6' class='gallery galleryid-48075 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-2.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-2-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-2-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-2-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-2-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-3.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-3-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-3-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-3-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-3-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-4.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-4-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-4-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-4-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-4-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-5.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-5-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-5-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-5-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-5-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-6.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-6-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-6-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-6-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-6-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-6-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-7.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-7-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-7-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-7-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-7-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-7-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-8.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-8-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-8-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-8-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-8-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-8-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-9.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-9-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-9-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-9-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-9-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-9-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-10.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-10-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-10-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-10-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-10-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-10-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-11.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-11-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-11-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-11-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-11-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-11-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-12.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-12-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-12-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-12-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-12-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-12-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-13.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-13-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-13-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-13-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-13-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-13-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-14.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-14-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-14-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-14-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-14-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-14-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-15.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-15-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-15-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-15-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-15-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-15-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-16.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-16-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-16-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-16-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-16-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-16-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-17.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-17-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-17-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-17-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-17-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-17-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-18.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-18-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-18-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-18-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-18-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-18-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-19.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-19-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-19-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-19-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-19-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-19-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-20.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-20-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-20-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-20-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-20-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-20-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-21.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-21-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-21-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-21-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-21-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-21-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-22.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-22-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-22-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-22-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-22-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-22-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-23.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-23-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-23-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-23-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-23-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-23-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-24.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-24-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-24-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-24-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-24-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-24-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-25.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-25-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-25-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-25-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-25-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-25-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-26.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-26-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-26-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-26-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-26-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-26-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-27.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-27-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-27-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-27-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-27-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-27-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-28.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-28-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-28-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-28-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-28-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-28-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-29.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-29-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-29-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-29-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-29-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-29-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-30.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-30-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-30-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-30-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-30-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-30-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-31.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-31-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-31-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-31-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-31-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-31-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-32.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-32-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-32-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-32-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-32-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-32-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-33.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-33-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-33-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-33-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-33-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-33-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-34.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-34-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-34-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-34-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-34-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-34-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-35.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-35-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-35-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-35-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-35-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-35-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-36.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-36-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-36-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-36-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-36-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-36-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-37.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-37-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-37-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-37-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-37-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-37-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-38.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-38-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-38-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-38-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-38-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-38-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-39.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-39-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-39-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-39-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-39-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-39-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-40.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-40-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-40-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-40-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-40-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-40-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-41.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-41-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-41-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-41-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-41-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-41-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-42.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-42-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-42-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-42-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-42-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-42-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-43.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-43-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-43-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-43-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-43-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-43-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-44.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-44-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-44-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-44-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-44-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-44-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-47.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-47-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-47-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-47-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-47-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-47-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-48.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-48-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-48-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-48-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-48-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-48-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-49.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-49-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-49-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-49-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-49-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-49-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-50.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-50-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-50-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-50-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-50-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-50-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-51.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-51-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-51-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-51-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-51-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-51-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-52.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-52-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-52-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-52-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-52-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-52-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-53.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-53-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-53-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-53-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-53-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-53-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-54.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-54-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-54-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-54-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-54-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-54-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-55.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-55-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-55-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-55-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-55-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-55-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-56.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-56-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-56-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-56-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-56-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-56-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-57.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-57-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-57-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-57-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-57-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-57-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-58.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-58-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-58-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-58-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-58-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-58-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-59.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-59-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-59-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-59-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-59-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-59-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-60.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-60-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-60-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-60-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-60-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-60-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-61.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-61-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-61-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-61-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-61-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-61-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-62.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-62-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-62-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-62-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-62-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-62-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-63.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-63-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-63-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-63-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-63-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-63-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-64.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-64-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-64-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-64-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-64-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-64-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-65.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-65-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-65-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-65-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-65-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-65-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-66.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-66-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-66-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-66-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-66-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-66-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-67.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-67-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-67-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-67-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-67-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-67-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-68.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-68-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-68-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-68-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-68-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-68-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-70.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-70-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-70-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-70-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-70-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-70-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-71.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-71-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-71-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-71-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-71-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-71-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-73.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-73-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-73-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-73-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-73-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-73-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-74.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-74-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-74-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-74-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-74-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-74-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-75.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-75-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-75-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-75-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-75-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-75-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-76.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-76-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-76-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-76-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-76-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-76-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-77.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-77-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-77-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-77-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-77-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-77-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-78.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-78-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-78-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-78-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-78-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-78-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-79.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-79-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-79-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-79-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-79-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-79-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-80.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-80-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-80-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-80-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-80-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-80-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-81.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-81-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-81-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-81-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-81-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-81-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-82.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-82-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-82-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-82-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-82-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-82-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-83.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-83-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-83-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-83-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-83-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-83-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-84.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-84-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-84-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-84-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-84-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-84-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-85.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-85-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-85-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-85-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-85-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-85-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-86.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-86-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-86-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-86-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-86-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-86-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-87.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-87-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-87-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-87-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-87-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-87-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-88.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-88-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-88-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-88-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-88-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-88-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-89.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-89-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-89-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-89-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-89-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-89-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-90.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-90-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-90-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-90-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-90-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-90-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-91.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-91-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-91-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-91-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-91-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-91-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-92.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-92-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-92-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-92-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-92-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-92-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-93.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-93-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-93-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-93-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-93-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-93-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-94.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-94-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-94-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-94-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-94-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-94-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-95.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-95-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-95-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-95-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-95-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-95-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-96.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-96-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-96-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-96-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-96-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-96-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-97.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-97-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-97-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-97-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-97-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-97-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-98.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-98-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-98-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-98-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-98-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-98-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-99.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-99-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-99-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-99-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-99-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-99-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-100.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-100-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-100-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-100-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-100-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-100-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-101.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-101-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-101-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-101-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-101-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-101-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-102.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-102-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-102-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-102-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-102-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-102-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-103.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-103-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-103-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-103-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-103-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-103-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-104.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-104-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-104-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-104-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-104-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-104-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-105.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-105-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-105-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-105-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-105-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-105-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-106.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-106-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-106-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-106-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-106-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-106-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-107.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-107-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-107-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-107-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-107-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-107-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-108.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-108-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-108-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-108-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-108-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-108-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-109.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-109-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-109-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-109-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-109-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-109-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-110.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-110-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-110-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-110-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-110-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-110-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-111.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-111-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-111-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-111-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-111-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-111-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-112.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-112-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-112-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-112-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-112-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-112-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-113.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-113-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-113-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-113-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-113-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-113-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-114.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-114-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-114-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-114-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-114-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-114-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-115.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-115-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-115-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-115-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-115-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-115-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-116.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-116-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-116-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-116-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-116-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-116-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-117.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-117-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-117-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-117-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-117-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-117-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-118.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-118-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-118-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-118-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-118-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-118-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-119.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-119-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-119-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-119-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-119-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-119-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-120.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-120-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-120-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-120-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-120-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-120-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-121.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-121-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-121-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-121-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-121-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-121-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-122.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-122-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-122-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-122-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-122-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-122-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-123.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-123-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-123-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-123-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-123-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-123-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-124.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-124-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-124-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-124-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-124-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-124-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-125.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-125-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-125-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-125-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-125-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-125-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-126.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-126-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-126-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-126-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-126-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-126-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-127.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-127-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-127-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-127-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-127-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-127-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-128.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-128-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-128-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-128-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-128-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-128-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-129.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-129-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-129-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-129-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-129-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-129-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-130.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-130-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-130-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-130-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-130-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-130-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-131.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-131-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-131-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-131-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-131-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-131-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-132.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-132-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-132-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-132-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-132-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-132-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-133.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-133-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-133-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-133-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-133-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-133-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-134.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-134-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-134-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-134-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-134-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-134-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-135.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-135-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-135-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-135-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-135-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-135-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-136.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-136-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-136-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-136-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-136-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-136-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-137.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-137-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-137-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-137-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-137-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-137-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-138.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-138-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-138-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-138-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-138-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-138-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-139.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-139-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-139-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-139-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-139-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-139-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-140.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-140-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-140-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-140-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-140-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-140-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-141.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-141-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-141-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-141-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-141-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-141-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-142.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-142-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-142-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-142-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-142-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-142-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-143.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-143-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-143-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-143-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-143-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-143-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-144.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-144-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-144-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-144-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-144-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-144-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-145.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-145-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-145-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-145-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-145-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-145-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-146.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-146-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-146-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-146-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-146-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-146-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-147.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-147-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-147-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-147-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-147-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-147-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-148.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-148-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-148-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-148-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-148-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-148-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-149.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-149-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-149-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-149-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-149-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-149-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-152.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-152-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-152-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-152-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-152-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-152-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-153.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-153-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-153-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-153-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-153-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-153-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-154.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-154-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-154-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-154-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-154-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-154-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-155.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-155-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-155-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-155-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-155-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-155-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-156.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-156-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-156-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-156-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-156-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-156-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-157.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-157-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-157-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-157-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-157-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-157-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-158.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-158-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-158-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-158-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-158-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-158-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-160.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-160-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-160-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-160-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-160-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-160-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-161.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-161-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-161-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-161-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-161-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-161-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-162.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-162-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-162-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-162-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-162-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-162-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-163.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-163-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-163-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-163-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-163-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-163-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-164.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-164-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-164-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-164-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-164-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-164-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-165.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-165-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-165-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-165-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-165-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-165-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-166.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-166-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-166-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-166-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-166-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-166-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-167.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-167-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-167-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-167-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-167-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-167-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-168.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-168-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-168-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-168-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-168-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-168-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-169.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-169-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-169-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-169-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-169-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-169-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-170.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-170-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-170-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-170-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-170-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-170-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-171.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-171-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-171-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-171-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-171-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-171-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-172.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-172-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-172-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-172-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-172-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-172-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-173.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-173-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-173-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-173-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-173-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-173-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-174.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-174-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-174-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-174-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-174-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-174-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-175.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-175-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-175-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-175-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-175-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-175-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-176.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-176-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-176-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-176-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-176-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-176-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-178.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-178-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-178-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-178-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-178-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-178-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-179.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-179-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-179-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-179-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-179-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-179-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-180.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-180-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-180-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-180-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-180-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-180-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-181.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-181-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-181-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-181-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-181-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-181-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-182.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-182-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-182-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-182-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-182-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-182-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-184.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-184-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-184-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-184-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-184-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-184-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-185.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-185-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-185-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-185-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-185-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-185-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-186.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-186-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-186-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-186-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-186-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-186-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-187.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-187-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-187-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-187-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-187-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-187-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-188.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-188-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-188-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-188-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-188-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-188-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-189.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-189-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-189-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-189-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-189-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-189-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-190.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-190-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-190-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-190-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-190-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-190-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-191.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-191-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-191-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-191-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-191-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-191-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-192.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-192-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-192-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-192-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-192-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-192-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-193.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-193-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-193-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-193-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-193-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-193-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-194.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-194-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-194-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-194-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-194-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-194-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-195.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-195-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-195-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-195-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-195-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-195-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-198.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-198-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-198-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-198-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-198-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-198-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-199.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-199-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-199-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-199-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-199-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-199-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-200.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-200-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-200-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-200-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-200-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-200-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-202.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-202-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-202-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-202-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-202-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-202-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-203.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-203-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-203-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-203-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-203-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-203-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-204.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-204-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-204-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-204-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-204-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-204-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-205.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-205-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-205-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-205-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-205-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-205-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-206.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-206-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-206-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-206-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-206-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-206-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-207.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-207-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-207-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-207-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-207-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-207-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-208.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-208-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-208-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-208-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-208-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-208-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-209.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-209-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-209-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-209-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-209-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-209-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-210.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-210-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-210-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-210-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-210-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-210-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-211.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-211-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-211-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-211-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-211-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-211-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-212.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-212-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-212-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-212-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-212-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-212-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-213.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-213-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-213-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-213-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-213-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-213-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-214.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-214-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-214-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-214-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-214-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-214-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-215.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-215-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-215-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-215-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-215-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-215-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-216.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-216-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-216-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-216-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-216-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-216-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-217.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-217-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-217-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-217-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-217-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-217-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-218.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-218-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-218-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-218-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-218-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-218-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-219.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-219-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-219-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-219-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-219-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-219-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-220.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-220-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-220-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-220-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-220-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-220-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-221.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-221-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-221-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-221-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-221-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-221-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-222.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-222-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-222-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-222-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-222-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-222-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-223.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-223-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-223-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-223-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-223-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-223-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-224.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-224-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-224-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-224-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-224-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-224-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-225.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-225-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-225-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-225-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-225-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-225-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-226.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-226-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-226-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-226-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-226-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-226-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-227.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-227-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-227-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-227-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-227-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-227-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-228.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-228-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-228-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-228-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-228-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-228-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-229.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-229-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-229-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-229-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-229-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-229-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-230.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-230-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-230-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-230-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-230-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-230-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-231.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-231-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-231-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-231-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-231-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-231-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-232.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-232-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-232-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-232-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-232-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-232-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-233.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-233-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-233-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-233-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-233-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-233-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-234.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-234-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-234-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-234-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-234-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-234-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-235.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-235-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-235-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-235-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-235-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-235-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-236.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-236-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-236-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-236-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-236-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-236-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-237.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-237-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-237-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-237-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-237-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-237-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-238.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-238-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-238-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-238-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-238-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-238-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-239.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-239-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-239-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-239-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-239-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-239-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-240.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-240-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-240-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-240-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-240-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-240-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-241.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-241-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-241-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-241-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-241-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-241-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-242.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-242-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-242-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-242-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-242-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-242-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-243.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-243-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-243-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-243-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-243-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-243-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-244.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-244-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-244-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-244-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-244-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-244-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-245.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-245-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-245-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-245-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-245-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-245-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-246.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-246-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-246-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-246-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-246-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-246-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-247.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-247-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-247-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-247-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-247-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-247-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-248.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-248-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-248-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-248-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-248-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-248-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-249.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-249-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-249-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-249-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-249-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-249-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-250.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-250-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-250-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-250-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-250-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-250-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-251.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-251-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-251-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-251-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-251-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-251-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-252.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-252-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-252-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-252-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-252-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-252-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-253.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-253-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-253-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-253-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-253-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-253-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-254.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-254-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-254-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-254-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-254-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-254-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-255.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-255-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-255-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-255-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-255-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-255-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-256.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-256-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-256-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-256-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-256-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-256-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-257.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-257-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-257-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-257-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-257-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Ride-Logo-257-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6082.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6082-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6082-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6082-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6082-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6082-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6083.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6083-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6083-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6083-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6083-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6083-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6085.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6085-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6085-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6085-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6085-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6085-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6086.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6086-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6086-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6086-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6086-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6086-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6088.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6088-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6088-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6088-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6088-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6088-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6099.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6099-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6099-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6099-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6099-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6099-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6101.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6101-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6101-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6101-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6101-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6101-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n[\/vc_tab][vc_tab title=&#8221;L&#8217;arrivo&#8221; tab_id=&#8221;1513178049026-3-51513247018481&#8243;]<div id='gallery-7' class='gallery galleryid-48075 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-2.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-2-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-2-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-2-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-2-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-3.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-3-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-3-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-3-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-3-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-4.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-4-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-4-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-4-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-4-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-5.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-5-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-5-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-5-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-5-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-6.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-6-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-6-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-6-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-6-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-6-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-10.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-10-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-10-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-10-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-10-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-10-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-11.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-11-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-11-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-11-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-11-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-11-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-12.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-12-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-12-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-12-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-12-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-12-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-13.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-13-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-13-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-13-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-13-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-13-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-14.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-14-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-14-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-14-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-14-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-14-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-15.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-15-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-15-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-15-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-15-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-15-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-16.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-16-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-16-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-16-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-16-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-16-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-18.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-18-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-18-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-18-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-18-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-18-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-19.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-19-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-19-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-19-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-19-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-19-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-20.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-20-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-20-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-20-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-20-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-20-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-21.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-21-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-21-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-21-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-21-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-21-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-22.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-22-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-22-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-22-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-22-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-22-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-23.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-23-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-23-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-23-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-23-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-23-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-24.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-24-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-24-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-24-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-24-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-24-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-25.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-25-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-25-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-25-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-25-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-25-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-26.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-26-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-26-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-26-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-26-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-26-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-27.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-27-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-27-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-27-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-27-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-27-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-28.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-28-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-28-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-28-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-28-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-28-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-29.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-29-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-29-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-29-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-29-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-29-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-30.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-30-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-30-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-30-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-30-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-30-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-31.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-31-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-31-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-31-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-31-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-31-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-32.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-32-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-32-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-32-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-32-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-32-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-33.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-33-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-33-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-33-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-33-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-33-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-34.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-34-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-34-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-34-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-34-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-34-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-35.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-35-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-35-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-35-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-35-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-35-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-36.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-36-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-36-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-36-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-36-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-36-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-37.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-37-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-37-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-37-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-37-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-37-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-38.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-38-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-38-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-38-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-38-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-38-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-39.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-39-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-39-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-39-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-39-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Post-Ride-Logo-39-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n<div id='gallery-8' class='gallery galleryid-48075 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6132.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6132-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6132-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6132-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6132-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6132-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6138.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6138-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6138-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6138-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6138-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6138-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6146.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6146-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6146-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6146-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6146-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6146-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6147.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6147-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6147-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6147-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6147-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6147-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6148.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6148-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6148-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6148-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6148-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6148-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6152.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6152-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6152-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6152-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6152-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6152-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6154.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6154-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6154-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6154-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6154-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6154-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6162.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6162-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6162-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6162-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6162-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6162-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6173.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6173-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6173-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6173-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6173-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6173-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6176.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6176-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6176-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6176-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6176-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6176-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6181.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6181-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6181-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6181-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6181-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6181-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6185.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6185-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6185-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6185-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6185-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6185-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6187.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6187-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6187-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6187-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6187-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6187-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6189.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6189-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6189-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6189-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6189-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6189-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6191.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6191-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6191-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6191-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6191-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6191-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6192.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6192-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6192-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6192-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6192-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6192-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6194.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6194-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6194-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6194-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6194-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6194-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6195.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6195-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6195-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6195-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6195-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6195-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6196.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6196-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6196-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6196-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6196-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6196-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6199.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6199-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6199-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6199-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6199-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6199-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6200.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6200-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6200-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6200-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6200-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6200-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6201.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6201-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6201-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6201-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6201-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6201-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6202.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6202-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6202-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6202-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6202-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6202-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6203.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6203-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6203-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6203-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6203-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6203-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6204.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6204-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6204-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6204-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6204-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6204-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6205.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6205-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6205-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6205-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6205-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6205-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6207.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6207-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6207-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6207-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6207-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6207-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6210.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6210-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6210-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6210-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6210-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6210-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6211.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6211-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6211-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6211-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6211-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6211-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6212.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6212-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6212-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6212-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6212-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6212-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6213.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6213-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6213-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6213-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6213-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6213-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6214.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6214-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6214-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6214-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6214-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6214-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6217.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6217-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6217-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6217-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6217-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6217-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6218.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6218-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6218-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6218-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6218-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6218-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6219.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6219-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6219-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6219-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6219-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6219-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6220.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6220-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6220-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6220-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6220-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6220-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6221.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6221-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6221-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6221-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6221-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6221-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6224.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6224-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6224-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6224-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6224-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6224-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6225.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6225-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6225-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6225-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6225-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6225-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6226.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6226-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6226-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6226-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6226-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6226-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6228.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6228-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6228-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6228-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6228-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6228-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6229.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6229-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6229-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6229-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6229-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6229-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6231.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6231-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6231-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6231-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6231-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6231-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6233.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6233-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6233-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6233-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6233-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6233-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6234.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6234-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6234-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6234-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6234-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6234-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6236.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6236-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6236-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6236-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6236-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6236-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6240.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6240-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6240-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6240-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6240-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6240-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6242.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6242-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6242-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6242-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6242-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6242-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6244.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6244-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6244-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6244-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6244-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6244-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6245.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6245-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6245-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6245-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6245-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6245-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6246.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6246-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6246-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6246-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6246-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6246-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6247.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6247-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6247-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6247-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6247-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6247-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6248.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6248-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6248-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6248-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6248-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6248-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6250.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6250-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6250-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6250-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6250-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6250-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6252.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6252-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6252-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6252-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6252-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6252-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6254.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6254-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6254-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6254-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6254-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6254-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6256.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6256-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6256-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6256-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6256-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6256-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6259.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6259-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6259-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6259-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6259-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6259-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6262.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6262-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6262-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6262-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6262-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6262-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6268.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6268-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6268-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6268-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6268-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6268-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6270.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6270-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6270-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6270-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6270-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6270-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6271.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6271-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6271-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6271-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6271-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6271-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6273.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6273-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6273-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6273-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6273-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6273-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6276.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6276-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6276-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6276-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6276-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6276-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6277.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6277-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6277-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6277-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6277-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6277-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6278.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6278-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6278-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6278-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6278-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6278-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6279.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6279-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6279-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6279-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6279-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6279-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6282.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6282-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6282-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6282-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6282-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6282-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6283.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6283-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6283-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6283-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6283-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6283-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6284.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6284-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6284-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6284-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6284-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6284-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6285.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6285-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6285-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6285-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6285-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6285-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6287.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6287-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6287-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6287-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6287-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6287-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6289.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6289-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6289-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6289-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6289-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6289-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6290.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6290-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6290-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6290-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6290-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6290-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6291.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6291-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6291-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6291-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6291-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6291-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6292.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6292-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6292-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6292-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6292-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6292-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6294.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6294-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6294-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6294-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6294-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6294-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6296.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6296-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6296-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6296-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6296-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6296-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6299.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6299-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6299-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6299-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6299-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6299-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6301.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6301-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6301-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6301-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6301-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6301-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6303.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6303-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6303-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6303-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6303-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6303-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6307.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6307-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6307-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6307-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6307-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6307-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6309.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6309-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6309-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6309-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6309-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6309-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6314.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6314-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6314-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6314-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6314-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6314-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6315.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6315-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6315-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6315-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6315-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6315-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6317.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6317-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6317-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6317-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6317-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6317-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6319.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6319-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6319-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6319-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6319-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6319-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6326.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6326-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6326-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6326-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6326-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6326-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6331.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6331-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6331-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6331-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6331-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6331-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6333.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6333-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6333-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6333-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6333-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6333-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6334.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6334-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6334-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6334-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6334-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6334-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6335.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6335-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6335-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6335-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6335-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6335-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6337.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6337-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6337-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6337-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6337-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6337-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6344.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6344-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6344-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6344-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6344-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6344-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6359.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6359-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6359-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6359-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6359-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6359-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6365.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6365-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6365-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6365-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6365-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6365-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6371.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6371-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6371-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6371-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6371-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Giulia-Paratelli-6371-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n[\/vc_tab][\/vc_tabs][\/vc_tabs][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column width=&#8221;1\/1&#8243;][uncode_block id=&#8221;34935&#8243;][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;0&#8243; bottom_padding=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column width=&#8221;1\/1&#8243;][vc_separator sep_color=&#8221;color-785073&#8243;][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;2&#8243; bottom_padding=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column width=&#8221;1\/3&#8243;][vc_custom_heading separator=&#8221;yes&#8221; el_class=&#8221;bikenight-titoletto&#8221;]Notizie[\/vc_custom_heading][\/vc_column][vc_column width=&#8221;2\/3&#8243;][uncode_index el_id=&#8221;index-774645&#8243; index_type=&#8221;carousel&#8221; loop=&#8221;size:3|order_by:date|post_type:post|categories:38&#8243; carousel_lg=&#8221;3&#8243; carousel_md=&#8221;3&#8243; carousel_sm=&#8221;1&#8243; gutter_size=&#8221;3&#8243; post_items=&#8221;media|featured|onpost|original,title,sep-one|reduced&#8221; carousel_interval=&#8221;3000&#8243; carousel_navspeed=&#8221;400&#8243; stage_padding=&#8221;0&#8243; single_overlay_color=&#8221;color-197741&#8243; single_overlay_opacity=&#8221;50&#8243; single_padding=&#8221;2&#8243; el_class=&#8221;notizie&#8221;][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;0&#8243; bottom_padding=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column width=&#8221;1\/1&#8243;][vc_separator sep_color=&#8221;color-785073&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/1&#8243;][uncode_block id=&#8221;34792&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row row_height_percent=&#8221;0&#8243; back_color=&#8221;color-121595&#8243; overlay_alpha=&#8221;50&#8243; equal_height=&#8221;yes&#8221; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; el_class=&#8221;bikenight-primariga&#8221;][vc_column column_width_percent=&#8221;100&#8243; style=&#8221;dark&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; medium_visibility=&#8221;yes&#8221; medium_width=&#8221;0&#8243; mobile_visibility=&#8221;yes&#8221; mobile_width=&#8221;0&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34129,"parent":34797,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-48075","page","type-page","status-publish","has-post-thumbnail","hentry","page_category-bike-night-en","page_category-edizioni-passate-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bike Night Bolzano - Resia 2017 - Witoor | Bike Night, Randonn\u00e9e Rando Imperator<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/witoor.com\/en\/bike-night\/bike-night-suedtirol\/bolzano-resia-2017\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bike Night Bolzano - Resia 2017 - Witoor | Bike Night, Randonn\u00e9e Rando Imperator\" \/>\n<meta property=\"og:description\" content=\"[vc_row row_height_percent=&#8221;0&#8243; back_color=&#8221;color-121595&#8243; overlay_alpha=&#8221;50&#8243; equal_height=&#8221;yes&#8221; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; el_class=&#8221;bikenight-primariga&#8221;][vc_column column_width_percent=&#8221;100&#8243; style=&#8221;dark&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; medium_visibility=&#8221;yes&#8221; medium_width=&#8221;0&#8243; mobile_visibility=&#8221;yes&#8221; mobile_width=&#8221;0&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/witoor.com\/en\/bike-night\/bike-night-suedtirol\/bolzano-resia-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Witoor | Bike Night, Randonn\u00e9e Rando Imperator\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/witoor.bikenight\/\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-11T21:02:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/11\/BGH_0961.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@witoorbiketours\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/bike-night-suedtirol\\\/bolzano-resia-2017\\\/\",\"url\":\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/bike-night-suedtirol\\\/bolzano-resia-2017\\\/\",\"name\":\"Bike Night Bolzano - Resia 2017 - Witoor | Bike Night, Randonn\u00e9e Rando Imperator\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/witoor.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/bike-night-suedtirol\\\/bolzano-resia-2017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/bike-night-suedtirol\\\/bolzano-resia-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/witoor.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/BGH_0961.jpg\",\"datePublished\":\"2017-12-16T14:25:43+00:00\",\"dateModified\":\"2018-01-11T21:02:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/bike-night-suedtirol\\\/bolzano-resia-2017\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/bike-night-suedtirol\\\/bolzano-resia-2017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/bike-night-suedtirol\\\/bolzano-resia-2017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/witoor.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/BGH_0961.jpg\",\"contentUrl\":\"https:\\\/\\\/witoor.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/BGH_0961.jpg\",\"width\":2000,\"height\":1333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/bike-night-suedtirol\\\/bolzano-resia-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/witoor.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bike Night\",\"item\":\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bike Night S\u00fcdtirol\",\"item\":\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/bike-night-suedtirol\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Bike Night Bolzano &#8211; Resia 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/witoor.com\\\/#website\",\"url\":\"https:\\\/\\\/witoor.com\\\/\",\"name\":\"Witoor | Bike Night, Randonn\u00e9e Rando Imperator\",\"description\":\"Experience Real Cycling\",\"publisher\":{\"@id\":\"https:\\\/\\\/witoor.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/witoor.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/witoor.com\\\/#organization\",\"name\":\"Witoor\",\"url\":\"https:\\\/\\\/witoor.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/witoor.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/witoor.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/witoor-logo-viola.png\",\"contentUrl\":\"https:\\\/\\\/witoor.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/witoor-logo-viola.png\",\"width\":700,\"height\":255,\"caption\":\"Witoor\"},\"image\":{\"@id\":\"https:\\\/\\\/witoor.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/witoor.bikenight\\\/\",\"https:\\\/\\\/x.com\\\/witoorbiketours\",\"http:\\\/\\\/instagram.com\\\/witoor\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bike Night Bolzano - Resia 2017 - Witoor | Bike Night, Randonn\u00e9e Rando Imperator","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/witoor.com\/en\/bike-night\/bike-night-suedtirol\/bolzano-resia-2017\/","og_locale":"en_US","og_type":"article","og_title":"Bike Night Bolzano - Resia 2017 - Witoor | Bike Night, Randonn\u00e9e Rando Imperator","og_description":"[vc_row row_height_percent=&#8221;0&#8243; back_color=&#8221;color-121595&#8243; overlay_alpha=&#8221;50&#8243; equal_height=&#8221;yes&#8221; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; el_class=&#8221;bikenight-primariga&#8221;][vc_column column_width_percent=&#8221;100&#8243; style=&#8221;dark&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; medium_visibility=&#8221;yes&#8221; medium_width=&#8221;0&#8243; mobile_visibility=&#8221;yes&#8221; mobile_width=&#8221;0&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; [&hellip;]","og_url":"https:\/\/witoor.com\/en\/bike-night\/bike-night-suedtirol\/bolzano-resia-2017\/","og_site_name":"Witoor | Bike Night, Randonn\u00e9e Rando Imperator","article_publisher":"http:\/\/www.facebook.com\/witoor.bikenight\/","article_modified_time":"2018-01-11T21:02:03+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/11\/BGH_0961.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@witoorbiketours","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/witoor.com\/en\/bike-night\/bike-night-suedtirol\/bolzano-resia-2017\/","url":"https:\/\/witoor.com\/en\/bike-night\/bike-night-suedtirol\/bolzano-resia-2017\/","name":"Bike Night Bolzano - Resia 2017 - Witoor | Bike Night, Randonn\u00e9e Rando Imperator","isPartOf":{"@id":"https:\/\/witoor.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/witoor.com\/en\/bike-night\/bike-night-suedtirol\/bolzano-resia-2017\/#primaryimage"},"image":{"@id":"https:\/\/witoor.com\/en\/bike-night\/bike-night-suedtirol\/bolzano-resia-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/11\/BGH_0961.jpg","datePublished":"2017-12-16T14:25:43+00:00","dateModified":"2018-01-11T21:02:03+00:00","breadcrumb":{"@id":"https:\/\/witoor.com\/en\/bike-night\/bike-night-suedtirol\/bolzano-resia-2017\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/witoor.com\/en\/bike-night\/bike-night-suedtirol\/bolzano-resia-2017\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/witoor.com\/en\/bike-night\/bike-night-suedtirol\/bolzano-resia-2017\/#primaryimage","url":"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/11\/BGH_0961.jpg","contentUrl":"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/11\/BGH_0961.jpg","width":2000,"height":1333},{"@type":"BreadcrumbList","@id":"https:\/\/witoor.com\/en\/bike-night\/bike-night-suedtirol\/bolzano-resia-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/witoor.com\/en\/"},{"@type":"ListItem","position":2,"name":"Bike Night","item":"https:\/\/witoor.com\/en\/bike-night\/"},{"@type":"ListItem","position":3,"name":"Bike Night S\u00fcdtirol","item":"https:\/\/witoor.com\/en\/bike-night\/bike-night-suedtirol\/"},{"@type":"ListItem","position":4,"name":"Bike Night Bolzano &#8211; Resia 2017"}]},{"@type":"WebSite","@id":"https:\/\/witoor.com\/#website","url":"https:\/\/witoor.com\/","name":"Witoor | Bike Night, Randonn\u00e9e Rando Imperator","description":"Experience Real Cycling","publisher":{"@id":"https:\/\/witoor.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/witoor.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/witoor.com\/#organization","name":"Witoor","url":"https:\/\/witoor.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/witoor.com\/#\/schema\/logo\/image\/","url":"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/11\/witoor-logo-viola.png","contentUrl":"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/11\/witoor-logo-viola.png","width":700,"height":255,"caption":"Witoor"},"image":{"@id":"https:\/\/witoor.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/witoor.bikenight\/","https:\/\/x.com\/witoorbiketours","http:\/\/instagram.com\/witoor"]}]}},"_links":{"self":[{"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/pages\/48075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/comments?post=48075"}],"version-history":[{"count":2,"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/pages\/48075\/revisions"}],"predecessor-version":[{"id":57110,"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/pages\/48075\/revisions\/57110"}],"up":[{"embeddable":true,"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/pages\/34797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/media\/34129"}],"wp:attachment":[{"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/media?parent=48075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}