{"id":39921,"date":"2017-12-12T15:04:55","date_gmt":"2017-12-12T14:04:55","guid":{"rendered":"https:\/\/witoor.com\/web\/bike-night\/bike-night-udine-alpe-adria\/udine-alpeadria-2016\/"},"modified":"2020-02-26T15:21:43","modified_gmt":"2020-02-26T14:21:43","slug":"alpeadria-2016","status":"publish","type":"page","link":"https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/","title":{"rendered":"Bike Night Udine &#8211; Alpe Adria 2016"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row row_height_percent=&#8221;0&#8243; back_color=&#8221;color-121595&#8243; overlay_alpha=&#8221;50&#8243; equal_height=&#8221;yes&#8221; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; el_class=&#8221;bikenight-primariga&#8221;][vc_column column_width_percent=&#8221;100&#8243; style=&#8221;dark&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; medium_visibility=&#8221;yes&#8221; medium_width=&#8221;0&#8243; mobile_visibility=&#8221;yes&#8221; mobile_width=&#8221;0&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; width=&#8221;1\/3&#8243; el_class=&#8221;intestazione-bikenight&#8221;][vc_custom_heading heading_semantic=&#8221;h4&#8243; text_size=&#8221;h5&#8243; separator=&#8221;yes&#8221; sub_reduced=&#8221;yes&#8221; el_class=&#8221;bikenight-titoletto&#8221;]sabato 20<br \/>\ndomenica 21<br \/>\nagosto 2016[\/vc_custom_heading][vc_column_text]<\/p>\n<h5><span class=\"font-127064\">Udine &#8211; Alpe Adria (Ugovizza)<\/span><\/h5>\n<p><em>villaggio partenza <\/em>piazza Libert\u00e0<em><br \/>\napertura<\/em>\u00a0ore 18.00<br \/>\n<em>via!<\/em> ore 24.00<\/p>\n<hr class=\"separator-break\" \/>\n<p>[\/vc_column_text][\/vc_column][vc_column column_width_percent=&#8221;100&#8243; style=&#8221;dark&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; width=&#8221;1\/3&#8243;][vc_column_text]<strong>Distanza<\/strong> 100km lungo l&#8217;Alpe Adria<br \/>\n<strong>Dislivello<\/strong>\u00a0+1100 m<br \/>\n<strong>Manto stradale<\/strong> Asfalto, sterrato nei primi 30km sull&#8217;ippovia[\/vc_column_text][vc_column_text]<strong>Partecipanti<\/strong>\u00a0220[\/vc_column_text][\/vc_column][vc_column column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; style=&#8221;dark&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; width=&#8221;1\/3&#8243;][vc_button button_color=&#8221;color-203025&#8243; radius=&#8221;btn-square&#8221; border_animation=&#8221;btn-ripple-out&#8221; wide=&#8221;yes&#8221; hover_fx=&#8221;outlined&#8221; outline=&#8221;yes&#8221; border_width=&#8221;0&#8243; link=&#8221;url:%23foto|title:Foto||&#8221;]Foto[\/vc_button][vc_button button_color=&#8221;color-203025&#8243; radius=&#8221;btn-square&#8221; border_animation=&#8221;btn-ripple-out&#8221; wide=&#8221;yes&#8221; hover_fx=&#8221;outlined&#8221; outline=&#8221;yes&#8221; border_width=&#8221;0&#8243; link=&#8221;url:https%3A%2F%2Fvimeo.com%2F179721501|title:Video||&#8221;]Video[\/vc_button][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;2&#8243; bottom_padding=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; desktop_visibility=&#8221;yes&#8221; medium_visibility=&#8221;yes&#8221; mobile_visibility=&#8221;yes&#8221; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column column_width_percent=&#8221;100&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; medium_visibility=&#8221;yes&#8221; medium_width=&#8221;0&#8243; mobile_visibility=&#8221;yes&#8221; mobile_width=&#8221;0&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; width=&#8221;1\/3&#8243;][vc_custom_heading separator=&#8221;yes&#8221; el_class=&#8221;bikenight-titoletto&#8221;]La passione per la bici non dorme mai![\/vc_custom_heading][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text]<strong>Bike Night \u00e8 un evento che unisce la bici, la\u00a0passione e le persone.<\/strong>\u00a0Giunta alla quarta edizione, la Bike Night Ferrara-Mare accende l\u2019estate: nel 2016 1500 persone hanno pedalato dalla citt\u00e0 lungo il Po.<\/p>\n<p><strong>La Bike Night Ferrara \u2013 Mare inaugura\u00a0l\u2019estate e le porte dei nostri sogni<\/strong>: dalla citt\u00e0 si pedala lungo l\u2019argine del Grande Fiume, percorrendo la ciclabile Destra Po fino al Delta, per poi arrivare a Lido di Volano, in riva al mare. Un\u2019esperienza unica affrontata in tanti modi diversi: in gruppo, in tandem, in monociclo, colorati o semplicemente s\u00e9 stessi, almeno per una notte.<\/p>\n<p><strong>L\u2019edizione 2017 vedr\u00e0 confermato il percorso con 100km tutti pianeggianti, tre ristori, la colazione all\u2019arrivo<\/strong>: vivi l\u2019attesa della mezzanotte insieme a noi al Villaggio Partenza! Le iscrizioni sono aperte e saranno a numero limitato: 1500 posti disponibili.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_icon position=&#8221;left&#8221; icon=&#8221;fa fa-image&#8221; icon_color=&#8221;color-197741&#8243; background_style=&#8221;fa-squared&#8221; heading_semantic=&#8221;h5&#8243; text_size=&#8221;h5&#8243; linked_title=&#8221;yes&#8221; title=&#8221;Edizione 2017 &#8211; Foto&#8221; link=&#8221;url:https%3A%2F%2Fwitoor.com%2Fbike-night%2Fbike-night-ferrara-mare%2Fferrara-mare-2017%2F|title:Foto%20Bike%20Night%202017||&#8221;][\/vc_icon][vc_icon position=&#8221;left&#8221; icon=&#8221;fa fa-video&#8221; icon_color=&#8221;color-197741&#8243; background_style=&#8221;fa-squared&#8221; heading_semantic=&#8221;h5&#8243; text_size=&#8221;h5&#8243; linked_title=&#8221;yes&#8221; title=&#8221;Edizione 2017 &#8211; Video&#8221; link=&#8221;url:https%3A%2F%2Fvimeo.com%2F222272675|title:Video%20Bike%20Night%202017||&#8221;][\/vc_icon][vc_icon position=&#8221;left&#8221; icon=&#8221;fa fa-map3&#8243; icon_color=&#8221;color-197741&#8243; background_style=&#8221;fa-squared&#8221; heading_semantic=&#8221;h5&#8243; text_size=&#8221;h5&#8243; linked_title=&#8221;yes&#8221; title=&#8221;Il percorso&#8221; link=&#8221;url:%23percorso|title:percorso%20Bike%20Night%20Ferrara%20Mare||&#8221;]Ferrara, la Destra Po, il Delta, il mare[\/vc_icon][vc_icon position=&#8221;left&#8221; icon=&#8221;fa fa-edit&#8221; icon_color=&#8221;color-197741&#8243; background_style=&#8221;fa-squared&#8221; heading_semantic=&#8221;h5&#8243; text_size=&#8221;h5&#8243; linked_title=&#8221;yes&#8221; title=&#8221;Partecipa alla Bike Night&#8221; link=&#8221;url:%23iscrizione|title:iscrizione%20Bike%20Night%20Ferrara%20Mare||&#8221;]100km in bici, 3 ristori, colazione e doccia all&#8217;arrivo, trasporto bagagli, assistenza meccanica e medica[\/vc_icon][vc_icon position=&#8221;left&#8221; icon=&#8221;fa fa-plus&#8221; icon_color=&#8221;color-197741&#8243; background_style=&#8221;fa-squared&#8221; heading_semantic=&#8221;h5&#8243; text_size=&#8221;h5&#8243; linked_title=&#8221;yes&#8221; title=&#8221;Scopri i nostri servizi&#8221; link=&#8221;url:%23servizi|title:iscrizione%20Bike%20Night%20Ferrara%20Mare||&#8221;]Noleggio bici e casco, assicurazione, parcheggio all&#8217;arrivo, navetta di rientro[\/vc_icon][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; equal_height=&#8221;yes&#8221; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; row_name=&#8221;percorso&#8221;][vc_column column_width_percent=&#8221;100&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; medium_visibility=&#8221;yes&#8221; medium_width=&#8221;0&#8243; mobile_visibility=&#8221;yes&#8221; mobile_width=&#8221;0&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; width=&#8221;1\/3&#8243;][vc_custom_heading separator=&#8221;yes&#8221; el_class=&#8221;bikenight-titoletto&#8221;]Il percorso[\/vc_custom_heading][vc_column_text]<strong>Udine<\/strong><br \/>\nippovia fino a Buja, Gemona del Friuli<br \/>\n<strong>Ciclovia Alpe Adria<\/strong><br \/>\nVenzone, uno dei Borghi pi\u00f9 belli d\u2019Italia<br \/>\n<strong>L\u2019antica ferrovia<\/strong><br \/>\nChiusaforte, arrivo e colazione all\u2019antica stazione di Ugovizza.[\/vc_column_text][vc_icon position=&#8221;left&#8221; icon=&#8221;fa fa-map-marker&#8221; icon_color=&#8221;color-121595&#8243; background_style=&#8221;fa-squared&#8221; heading_semantic=&#8221;p&#8221; text_size=&#8221;&#8221; linked_title=&#8221;yes&#8221; title=&#8221;Guarda il tracciato su Google Maps&#8221; link=&#8221;url:https%3A%2F%2Fwww.google.com%2Fmaps%2Fd%2Fviewer%3Fmid%3D1C5T6UeFRtqZJDqlU2IAmAVbz-88%26usp%3Dsharing|title:percorso%20Bike%20Night|target:%20_blank|&#8221;][\/vc_icon][\/vc_column][vc_column column_width_percent=&#8221;100&#8243; expand_height=&#8221;yes&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; width=&#8221;2\/3&#8243;][vc_raw_html]JTNDZGl2JTIwaWQlM0QlMjJtYXBwYSUyMiUyMGNsYXNzJTNEJTIyYmlrZW5pZ2h0LW1hcHBhJTIyJTNFJTNDJTJGZGl2JTNFJTBBJTNDc2NyaXB0JTNFJTBBJTIwJTIwdmFyJTIwbWFwJTNCJTBBJTIwJTIwdmFyJTIwc3JjJTIwJTNEJTIwJTI3aHR0cHMlM0ElMkYlMkZ3d3cud2l0b29yLmNvbSUyRmZpbGVzJTJGdHJhY2NlJTJGYmlrZW5pZ2h0LXVkLXRyYWNjaWEua216JTI3JTNCJTBBJTBBJTIwJTIwZnVuY3Rpb24lMjBpbml0TWFwJTI4JTI5JTIwJTdCJTBBJTIwJTIwJTIwJTIwbWFwJTIwJTNEJTIwbmV3JTIwZ29vZ2xlLm1hcHMuTWFwJTI4ZG9jdW1lbnQuZ2V0RWxlbWVudEJ5SWQlMjglMjdtYXBwYSUyNyUyOSUyQyUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMGNlbnRlciUzQSUyMG5ldyUyMGdvb2dsZS5tYXBzLkxhdExuZyUyODQ0LjQzNDA3NyUyQyUyMDEwLjkyNjc1OSUyOSUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMHpvb20lM0ElMjA5JTJDJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTJGJTJGbWFwVHlwZUlkJTNBJTIwJTI3dGVycmFpbiUyNyUwQSUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcyUzQSUyMCU1QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QmVsZW1lbnRUeXBlJTNBJTIwJTI3Z2VvbWV0cnklMjclMkMlMjBzdHlsZXJzJTNBJTIwJTVCJTdCY29sb3IlM0ElMjAlMjclMjMyNDJmM2UlMjclN0QlNUQlN0QlMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlN0JlbGVtZW50VHlwZSUzQSUyMCUyN2xhYmVscy50ZXh0LnN0cm9rZSUyNyUyQyUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyMzI0MmYzZSUyNyU3RCU1RCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QmVsZW1lbnRUeXBlJTNBJTIwJTI3bGFiZWxzLnRleHQuZmlsbCUyNyUyQyUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyMzc0Njg1NSUyNyU3RCU1RCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGZlYXR1cmVUeXBlJTNBJTIwJTI3YWRtaW5pc3RyYXRpdmUubG9jYWxpdHklMjclMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBlbGVtZW50VHlwZSUzQSUyMCUyN2xhYmVscy50ZXh0LmZpbGwlMjclMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBzdHlsZXJzJTNBJTIwJTVCJTdCY29sb3IlM0ElMjAlMjclMjNkNTk1NjMlMjclN0QlNUQlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlN0QlMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlN0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBmZWF0dXJlVHlwZSUzQSUyMCUyN3BvaSUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGVsZW1lbnRUeXBlJTNBJTIwJTI3bGFiZWxzLnRleHQuZmlsbCUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyM2Q1OTU2MyUyNyU3RCU1RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGZlYXR1cmVUeXBlJTNBJTIwJTI3cG9pLnBhcmslMjclMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBlbGVtZW50VHlwZSUzQSUyMCUyN2dlb21ldHJ5JTI3JTJDJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwc3R5bGVycyUzQSUyMCU1QiU3QmNvbG9yJTNBJTIwJTI3JTIzMjYzYzNmJTI3JTdEJTVEJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTdEJTJDJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTdCJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwZmVhdHVyZVR5cGUlM0ElMjAlMjdwb2kucGFyayUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGVsZW1lbnRUeXBlJTNBJTIwJTI3bGFiZWxzLnRleHQuZmlsbCUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyMzZiOWE3NiUyNyU3RCU1RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGZlYXR1cmVUeXBlJTNBJTIwJTI3cm9hZCUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGVsZW1lbnRUeXBlJTNBJTIwJTI3Z2VvbWV0cnklMjclMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBzdHlsZXJzJTNBJTIwJTVCJTdCY29sb3IlM0ElMjAlMjclMjMzODQxNGUlMjclN0QlNUQlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlN0QlMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlN0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBmZWF0dXJlVHlwZSUzQSUyMCUyN3JvYWQlMjclMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBlbGVtZW50VHlwZSUzQSUyMCUyN2dlb21ldHJ5LnN0cm9rZSUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyMzIxMmEzNyUyNyU3RCU1RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGZlYXR1cmVUeXBlJTNBJTIwJTI3cm9hZCUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGVsZW1lbnRUeXBlJTNBJTIwJTI3bGFiZWxzLnRleHQuZmlsbCUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyMzljYTViMyUyNyU3RCU1RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGZlYXR1cmVUeXBlJTNBJTIwJTI3cm9hZC5oaWdod2F5JTI3JTJDJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwZWxlbWVudFR5cGUlM0ElMjAlMjdnZW9tZXRyeSUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyMzc0Njg1NSUyNyU3RCU1RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGZlYXR1cmVUeXBlJTNBJTIwJTI3cm9hZC5oaWdod2F5JTI3JTJDJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwZWxlbWVudFR5cGUlM0ElMjAlMjdnZW9tZXRyeS5zdHJva2UlMjclMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBzdHlsZXJzJTNBJTIwJTVCJTdCY29sb3IlM0ElMjAlMjclMjMxZjI4MzUlMjclN0QlNUQlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlN0QlMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlN0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBmZWF0dXJlVHlwZSUzQSUyMCUyN3JvYWQuaGlnaHdheSUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGVsZW1lbnRUeXBlJTNBJTIwJTI3bGFiZWxzLnRleHQuZmlsbCUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyM2YzZDE5YyUyNyU3RCU1RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGZlYXR1cmVUeXBlJTNBJTIwJTI3dHJhbnNpdCUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGVsZW1lbnRUeXBlJTNBJTIwJTI3Z2VvbWV0cnklMjclMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBzdHlsZXJzJTNBJTIwJTVCJTdCY29sb3IlM0ElMjAlMjclMjMyZjM5NDglMjclN0QlNUQlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlN0QlMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlN0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBmZWF0dXJlVHlwZSUzQSUyMCUyN3RyYW5zaXQuc3RhdGlvbiUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGVsZW1lbnRUeXBlJTNBJTIwJTI3bGFiZWxzLnRleHQuZmlsbCUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyM2Q1OTU2MyUyNyU3RCU1RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGZlYXR1cmVUeXBlJTNBJTIwJTI3d2F0ZXIlMjclMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBlbGVtZW50VHlwZSUzQSUyMCUyN2dlb21ldHJ5JTI3JTJDJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwc3R5bGVycyUzQSUyMCU1QiU3QmNvbG9yJTNBJTIwJTI3JTIzMTcyNjNjJTI3JTdEJTVEJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTdEJTJDJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTdCJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwZmVhdHVyZVR5cGUlM0ElMjAlMjd3YXRlciUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGVsZW1lbnRUeXBlJTNBJTIwJTI3bGFiZWxzLnRleHQuZmlsbCUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyMzUxNWM2ZCUyNyU3RCU1RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3RCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMGZlYXR1cmVUeXBlJTNBJTIwJTI3d2F0ZXIlMjclMkMlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjBlbGVtZW50VHlwZSUzQSUyMCUyN2xhYmVscy50ZXh0LnN0cm9rZSUyNyUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHN0eWxlcnMlM0ElMjAlNUIlN0Jjb2xvciUzQSUyMCUyNyUyMzE3MjYzYyUyNyU3RCU1RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU3RCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCU1RCUwQSUyMCUyMCUyMCUyMCU3RCUyOSUzQiUwQSUwQSUyMCUyMCUyMCUyMHZhciUyMGttbExheWVyJTIwJTNEJTIwbmV3JTIwZ29vZ2xlLm1hcHMuS21sTGF5ZXIlMjhzcmMlMkMlMjAlN0IlMEElMjAlMjAlMjAlMjAlMjAlMjBzdXBwcmVzc0luZm9XaW5kb3dzJTNBJTIwdHJ1ZSUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMHByZXNlcnZlVmlld3BvcnQlM0ElMjBmYWxzZSUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMG1hcCUzQSUyMG1hcCUwQSUyMCUyMCUyMCUyMCU3RCUyOSUzQiUwQSUyMCUyMCU3RCUwQSUzQyUyRnNjcmlwdCUzRSUwQSUzQ3NjcmlwdCUyMGFzeW5jJTIwZGVmZXIlMEFzcmMlM0QlMjJodHRwcyUzQSUyRiUyRm1hcHMuZ29vZ2xlYXBpcy5jb20lMkZtYXBzJTJGYXBpJTJGanMlM0ZrZXklM0RBSXphU3lBbGZXSElNZ0J5ZHlGZWJXWnJRVmtfWEItcTlKdXpoRjQlMjZjYWxsYmFjayUzRGluaXRNYXAlMjIlM0UlMEElM0MlMkZzY3JpcHQlM0U=[\/vc_raw_html][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column width=&#8221;1\/3&#8243;][vc_custom_heading separator=&#8221;yes&#8221; el_class=&#8221;bikenight-titoletto&#8221;]Foto[\/vc_custom_heading][vc_column_text]Foto di Andrea Bighi e Giacomo Brini[\/vc_column_text][\/vc_column][vc_column width=&#8221;2\/3&#8243;][vc_tabs vertical=&#8221;yes&#8221;][vc_tab title=&#8221;L\u2019attesa in Piazza Libert\u00e0&#8221; tab_id=&#8221;1512639137-1-97&#8243;]<div id='gallery-1' class='gallery galleryid-39921 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8340_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8340_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8340_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8340_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8340_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8340_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8345_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8345_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8345_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8345_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8345_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8345_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8346_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8346_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8346_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8346_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8346_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8346_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8348_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8348_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8348_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8348_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8348_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8348_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8350_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8350_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8350_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8350_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8350_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8350_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8355_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8355_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8355_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8355_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8355_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8355_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8358_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8358_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8358_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8358_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8358_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8358_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8359_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8359_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8359_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8359_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8359_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8359_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8362_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8362_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8362_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8362_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8362_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8362_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8363_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8363_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8363_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8363_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8363_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8363_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8366_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8366_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8366_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8366_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8366_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8366_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8367_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8367_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8367_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8367_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8367_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8367_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8369_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8369_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8369_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8369_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8369_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8369_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8370_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8370_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8370_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8370_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8370_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8370_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8371_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8371_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8371_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8371_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8371_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8371_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8372_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8372_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8372_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8372_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8372_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8372_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8374_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8374_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8374_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8374_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8374_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8374_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8376_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8376_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8376_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8376_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8376_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8376_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8377_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8377_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8377_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8377_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8377_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8377_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8381_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8381_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8381_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8381_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8381_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8381_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8384_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8384_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8384_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8384_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8384_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8384_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8385_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8385_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8385_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8385_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8385_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8385_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8390_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8390_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8390_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8390_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8390_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8390_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8392_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8392_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8392_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8392_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8392_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8392_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8393_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8393_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8393_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8393_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8393_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8393_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8396_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8396_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8396_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8396_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8396_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8396_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8399_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8399_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8399_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8399_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8399_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8399_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8403_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8403_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8403_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8403_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8403_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8403_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8407_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8407_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8407_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8407_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8407_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8407_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8408_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8408_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8408_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8408_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8408_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8408_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8409_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8409_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8409_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8409_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8409_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8409_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8414_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8414_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8414_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8414_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8414_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8414_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8418_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8418_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8418_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8418_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8418_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8418_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8419_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8419_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8419_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8419_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8419_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8419_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8422_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8422_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8422_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8422_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8422_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8422_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8424_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8424_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8424_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8424_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8424_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8424_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8426_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8426_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8426_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8426_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8426_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8426_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8428_lt\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8428_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8428_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8428_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8428_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8428_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8430_lt\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8430_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8430_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8430_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8430_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8430_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8435_lt\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8435_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8435_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8435_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8435_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8435_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8439_lt\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8439_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8439_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8439_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8439_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8439_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8440_lt\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8440_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8440_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8440_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8440_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8440_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8445_lt\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8445_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8445_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8445_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8445_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8445_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8446_lt\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8446_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8446_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8446_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8446_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8446_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8449_lt\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8449_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8449_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8449_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8449_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8449_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8455_lt\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8455_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8455_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8455_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8455_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8455_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8456_lt\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8456_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8456_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8456_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8456_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8456_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8458_lt\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8458_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8458_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8458_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8458_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8458_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8460_lt\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8460_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8460_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8460_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8460_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8460_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8461_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8461_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8461_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8461_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8461_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8461_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8464_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8464_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8464_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8464_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8464_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8464_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8466_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8466_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8466_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8466_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8466_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8466_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8472_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8472_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8472_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8472_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8472_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8472_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8473_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8473_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8473_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8473_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8473_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8473_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8475_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8475_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8475_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8475_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8475_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8475_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8480_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8480_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8480_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8480_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8480_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8480_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8481_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8481_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8481_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8481_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8481_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8481_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8484_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8484_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8484_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8484_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8484_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8484_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8485_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8485_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8485_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8485_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8485_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8485_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8486_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8486_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8486_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8486_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8486_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8486_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8487_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8487_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8487_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8487_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8487_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8487_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8491_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8491_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8491_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8491_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8491_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8491_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8492_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8492_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8492_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8492_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8492_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8492_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8494_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8494_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8494_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8494_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8494_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8494_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8497_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8497_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8497_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8497_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8497_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8497_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8503_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8503_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8503_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8503_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8503_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8503_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8504_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8504_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8504_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8504_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8504_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8504_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8505_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8505_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8505_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8505_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8505_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8505_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8506_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8506_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8506_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8506_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8506_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8506_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8511_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8511_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8511_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8511_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8511_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8511_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8518_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8518_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8518_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8518_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8518_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8518_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8523_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8523_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8523_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8523_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8523_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8523_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8525_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8525_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8525_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8525_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8525_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8525_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8531_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8531_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8531_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8531_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8531_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8531_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8532_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8532_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8532_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8532_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8532_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8532_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8534_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8534_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8534_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8534_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8534_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8534_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8535_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8535_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8535_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8535_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8535_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8535_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8536_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8536_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8536_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8536_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8536_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8536_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8537_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8537_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8537_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8537_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8537_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8537_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8538_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8538_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8538_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8538_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8538_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8538_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8539_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8539_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8539_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8539_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8539_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8539_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8541_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8541_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8541_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8541_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8541_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8541_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8543_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8543_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8543_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8543_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8543_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8543_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8544_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8544_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8544_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8544_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8544_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8544_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8545_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8545_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8545_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8545_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8545_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8545_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8547_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8547_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8547_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8547_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8547_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8547_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8549_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8549_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8549_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8549_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8549_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8549_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8551_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8551_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8551_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8551_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8551_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8551_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8552_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8552_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8552_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8552_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8552_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8552_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8554_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8554_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8554_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8554_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8554_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8554_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8556_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8556_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8556_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8556_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8556_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8556_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8557_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8557_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8557_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8557_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8557_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8557_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8558_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8558_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8558_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8558_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8558_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8558_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8560_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8560_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8560_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8560_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8560_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8560_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8561_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8561_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8561_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8561_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8561_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8561_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8563_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8563_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8563_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8563_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8563_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8563_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8564_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8564_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8564_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8564_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8564_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8564_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8566_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8566_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8566_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8566_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8566_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8566_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8567_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8567_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8567_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8567_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8567_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8567_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8569_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8569_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8569_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8569_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8569_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8569_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8571_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8571_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8571_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8571_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8571_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8571_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8573_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8573_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8573_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8573_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8573_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8573_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8575_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8575_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8575_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8575_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8575_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8575_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n<div id='gallery-2' class='gallery galleryid-39921 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-001-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-001-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-001-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-001-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-001-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-002-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-002-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-002-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-002-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-002-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-002-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-003-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-003-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-003-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-003-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-003-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-003-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-004-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-004-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-004-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-004-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-004-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-004-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-005-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-005-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-005-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-005-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-005-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-005-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-006-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-006-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-006-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-006-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-006-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-006-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-007-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-007-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-007-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-007-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-007-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-007-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-008-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-008-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-008-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-008-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-008-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-008-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-009-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-009-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-009-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-009-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-009-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-009-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-010-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-010-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-010-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-010-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-010-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-010-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-011-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-011-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-011-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-011-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-011-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-011-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-012-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-012-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-012-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-012-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-012-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-012-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-013-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-013-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-013-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-013-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-013-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-013-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-014-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-014-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-014-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-014-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-014-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-014-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-015-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-015-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-015-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-015-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-015-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-015-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-016-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-016-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-016-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-016-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-016-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-016-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-017-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-017-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-017-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-017-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-017-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-017-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-018-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-018-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-018-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-018-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-018-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-018-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-019-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-019-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-019-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-019-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-019-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-019-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-020-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-020-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-020-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-020-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-020-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-020-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-021-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-021-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-021-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-021-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-021-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-021-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-022-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-022-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-022-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-022-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-022-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-022-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-023-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-023-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-023-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-023-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-023-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-023-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-024-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-024-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-024-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-024-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-024-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-024-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-025-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-025-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-025-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-025-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-025-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-025-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-026-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-026-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-026-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-026-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-026-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-026-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-027-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-027-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-027-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-027-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-027-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-027-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-028-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-028-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-028-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-028-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-028-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-028-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-029-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-029-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-029-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-029-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-029-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-029-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-030-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-030-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-030-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-030-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-030-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-030-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-031-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-031-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-031-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-031-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-031-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-031-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-032-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-032-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-032-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-032-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-032-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-032-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-033-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-033-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-033-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-033-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-033-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-033-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-034-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-034-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-034-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-034-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-034-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-034-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-035-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-035-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-035-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-035-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-035-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-035-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-036-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-036-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-036-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-036-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-036-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-036-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-037-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-037-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-037-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-037-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-037-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-037-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-038-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-038-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-038-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-038-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-038-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-038-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-039-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-039-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-039-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-039-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-039-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-039-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-040-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-040-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-040-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-040-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-040-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-040-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-041-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-041-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-041-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-041-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-041-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-041-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-042-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-042-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-042-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-042-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-042-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-042-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-043-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-043-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-043-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-043-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-043-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-043-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-044-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-044-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-044-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-044-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-044-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-044-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-045-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-045-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-045-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-045-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-045-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-045-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-046-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-046-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-046-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-046-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-046-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-046-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-047-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-047-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-047-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-047-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-047-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-047-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-048-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-048-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-048-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-048-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-048-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-048-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-049-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-049-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-049-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-049-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-049-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-049-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-050-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-050-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-050-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-050-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-050-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-050-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-051-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-051-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-051-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-051-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-051-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-051-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-052-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-052-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-052-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-052-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-052-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-052-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-053-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-053-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-053-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-053-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-053-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-053-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-054-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-054-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-054-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-054-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-054-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-054-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-055-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-055-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-055-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-055-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-055-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-055-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-056-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-056-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-056-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-056-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-056-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-056-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-057-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-057-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-057-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-057-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-057-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-057-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-058-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-058-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-058-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-058-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-058-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-058-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-059-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-059-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-059-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-059-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-059-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-059-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-060-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-060-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-060-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-060-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-060-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-060-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-061-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-061-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-061-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-061-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-061-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-061-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-062-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-062-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-062-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-062-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-062-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-062-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-063-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-063-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-063-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-063-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-063-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-063-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-064-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-064-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-064-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-064-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-064-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-064-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-065-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-065-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-065-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-065-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-065-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-065-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-066-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-066-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-066-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-066-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-066-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-066-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-067-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-067-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-067-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-067-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-067-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-067-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-068-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-068-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-068-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-068-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-068-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-068-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-069-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-069-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-069-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-069-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-069-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-069-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-070-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-070-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-070-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-070-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-070-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-070-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-071-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-071-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-071-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-071-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-071-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-071-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-072-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-072-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-072-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-072-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-072-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-072-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-073-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-073-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-073-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-073-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-073-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-073-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-074-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-074-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-074-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-074-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-074-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-074-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-075-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-075-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-075-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-075-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-075-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-075-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-076-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-076-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-076-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-076-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-076-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-076-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-077-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-077-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-077-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-077-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-077-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-077-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-078-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-078-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-078-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-078-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-078-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-078-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-079-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-079-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-079-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-079-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-079-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-079-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-080-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-080-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-080-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-080-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-080-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-080-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-081-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-081-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-081-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-081-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-081-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-081-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-082-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-082-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-082-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-082-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-082-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-082-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-083-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-083-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-083-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-083-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-083-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-083-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-084-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-084-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-084-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-084-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-084-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-084-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-085-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-085-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-085-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-085-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-085-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-085-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-086-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-086-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-086-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-086-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-086-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-086-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-087-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-087-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-087-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-087-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-087-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-087-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-088-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-088-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-088-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-088-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-088-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-088-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-089-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-089-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-089-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-089-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-089-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-089-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-090-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-090-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-090-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-090-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-090-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-090-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-091-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-091-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-091-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-091-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-091-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-091-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-092-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-092-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-092-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-092-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-092-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-092-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-093-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-093-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-093-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-093-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-093-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-093-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-094-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-094-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-094-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-094-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-094-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-094-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-231-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-231-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-231-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-231-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-231-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-231-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-232-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-232-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-232-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-232-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-232-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-232-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-233-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-233-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-233-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-233-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-233-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-233-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-235-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-235-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-235-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-235-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-235-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-235-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-238-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-238-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-238-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-238-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-238-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-238-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-239-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-239-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-239-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-239-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-239-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-239-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-240-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-240-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-240-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-240-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-240-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-240-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-247-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-247-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-247-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-247-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-247-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-247-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-248-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-248-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-248-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-248-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-248-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-248-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-249-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-249-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-249-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-249-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-249-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-249-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-252-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-252-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-252-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-252-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-252-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-252-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-253-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-253-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-253-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-253-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-253-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-253-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-254-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-254-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-254-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-254-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-254-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-254-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-255-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-255-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-255-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-255-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-255-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-255-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-256-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-256-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-256-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-256-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-256-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-256-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-257-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-257-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-257-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-257-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-257-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-257-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-258-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-258-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-258-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-258-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-258-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-258-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-259-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-259-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-259-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-259-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-259-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-259-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-260-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-260-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-260-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-260-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-260-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-260-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-261-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-261-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-261-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-261-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-261-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-261-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-263-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-263-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-263-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-263-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-263-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-263-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-264-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-264-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-264-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-264-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-264-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-264-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-265-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-265-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-265-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-265-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-265-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-265-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-267-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-267-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-267-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-267-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-267-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-267-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-231-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-231-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-231-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-231-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-231-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-231-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-232-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-232-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-232-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-232-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-232-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-232-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-233-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-233-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-233-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-233-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-233-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-233-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-235-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-235-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-235-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-235-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-235-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-235-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-238-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-238-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-238-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-238-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-238-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-238-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-239-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-239-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-239-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-239-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-239-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-239-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-240-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-240-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-240-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-240-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-240-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-240-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-247-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-247-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-247-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-247-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-247-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-247-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-248-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-248-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-248-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-248-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-248-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-248-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-249-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-249-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-249-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-249-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-249-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-249-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-252-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-252-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-252-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-252-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-252-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-252-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-253-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-253-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-253-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-253-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-253-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-253-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-254-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-254-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-254-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-254-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-254-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-254-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-255-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-255-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-255-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-255-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-255-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-255-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-256-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-256-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-256-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-256-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-256-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-256-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-257-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-257-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-257-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-257-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-257-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-257-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-258-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-258-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-258-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-258-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-258-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-258-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-259-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-259-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-259-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-259-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-259-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-259-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-260-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-260-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-260-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-260-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-260-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-260-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-261-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-261-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-261-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-261-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-261-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-261-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-263-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-263-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-263-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-263-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-263-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-263-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-264-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-264-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-264-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-264-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-264-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-264-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-265-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-265-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-265-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-265-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-265-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-265-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-267-2-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-267-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-267-1-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-267-1-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-267-1-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-267-1-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n[\/vc_tab][vc_tab title=&#8221;La partenza&#8221; tab_id=&#8221;1512639137-2-37&#8243;]<div id='gallery-3' class='gallery galleryid-39921 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8576_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8576_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8576_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8576_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8576_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8576_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8579_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8579_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8579_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8579_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8579_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8579_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8580_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8580_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8580_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8580_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8580_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8580_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8581_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8581_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8581_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8581_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8581_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8581_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8583_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8583_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8583_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8583_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8583_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8583_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8587_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8587_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8587_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8587_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8587_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8587_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8589_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8589_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8589_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8589_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8589_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8589_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8591_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8591_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8591_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8591_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8591_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8591_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8595_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8595_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8595_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8595_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8595_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8595_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8596_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8596_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8596_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8596_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8596_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8596_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8599_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8599_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8599_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8599_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8599_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8599_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8604_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8604_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8604_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8604_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8604_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8604_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8608_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8608_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8608_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8608_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8608_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8608_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8609_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8609_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8609_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8609_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8609_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8609_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8611_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8611_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8611_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8611_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8611_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8611_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8613_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8613_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8613_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8613_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8613_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8613_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8621_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8621_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8621_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8621_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8621_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8621_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8622_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8622_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8622_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8622_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8622_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8622_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8623_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8623_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8623_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8623_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8623_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8623_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8624_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8624_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8624_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8624_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8624_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8624_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-095-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-095-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-095-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-095-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-095-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-095-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-096-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-096-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-096-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-096-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-096-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-096-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-097-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-097-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-097-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-097-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-097-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-097-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-098-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-098-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-098-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-098-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-098-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-098-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-099-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-099-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-099-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-099-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-099-768x768.jpg 768w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-099-1024x1024.jpg 1024w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-099-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-099-600x600.jpg 600w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-099.jpg 1800w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-100-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-100-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-100-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-100-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-100-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-100-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-268-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-268-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-268-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-268-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-268-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-268-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-269-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-269-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-269-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-269-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-269-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-269-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-271-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-271-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-271-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-271-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-271-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-271-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-272-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-272-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-272-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-272-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-272-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-272-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-273-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-273-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-273-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-273-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-273-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-273-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-275-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-275-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-275-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-275-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-275-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-275-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-276-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-276-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-276-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-276-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-276-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-276-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-277-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-277-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-277-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-277-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-277-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-277-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-278-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-278-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-278-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-278-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-278-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-278-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-279-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-279-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-279-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-279-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-279-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-279-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-280-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-280-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-280-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-280-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-280-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-280-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n[\/vc_tab][vc_tab title=&#8221;Il percorso&#8221; tab_id=&#8221;1512639236989-2-8&#8243;]<div id='gallery-4' class='gallery galleryid-39921 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8626_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8626_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8626_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8626_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8626_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8626_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8628_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8628_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8628_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8628_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8628_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8628_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8638_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8638_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8638_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8638_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8638_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8638_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8640_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8640_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8640_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8640_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8640_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8640_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8641_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8641_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8641_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8641_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8641_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8641_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8644_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8644_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8644_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8644_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8644_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8644_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8646_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8646_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8646_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8646_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8646_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8646_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8647_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8647_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8647_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8647_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8647_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8647_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8649_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8649_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8649_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8649_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8649_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8649_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8650_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8650_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8650_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8650_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8650_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8650_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8653_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8653_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8653_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8653_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8653_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8653_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8654_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8654_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8654_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8654_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8654_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8654_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8655_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8655_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8655_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8655_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8655_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8655_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8657_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8657_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8657_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8657_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8657_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8657_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8660_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8660_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8660_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8660_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8660_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8660_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8661_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8661_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8661_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8661_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8661_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8661_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8663_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8663_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8663_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8663_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8663_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8663_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8665_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8665_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8665_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8665_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8665_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8665_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8667_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8667_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8667_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8667_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8667_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8667_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8669_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8669_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8669_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8669_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8669_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8669_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8671_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8671_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8671_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8671_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8671_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8671_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8672_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8672_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8672_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8672_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8672_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8672_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8674_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8674_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8674_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8674_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8674_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8674_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8678_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8678_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8678_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8678_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8678_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8678_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8680_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8680_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8680_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8680_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8680_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8680_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8681_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8681_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8681_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8681_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8681_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8681_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8684_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8684_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8684_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8684_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8684_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8684_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8686_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8686_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8686_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8686_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8686_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8686_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8690_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8690_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8690_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8690_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8690_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8690_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8692_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8692_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8692_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8692_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8692_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8692_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8693_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8693_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8693_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8693_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8693_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8693_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8694_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8694_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8694_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8694_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8694_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8694_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8701_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8701_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8701_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8701_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8701_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8701_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8707_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8707_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8707_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8707_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8707_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8707_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8712_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8712_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8712_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8712_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8712_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8712_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8713_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8713_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8713_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8713_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8713_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8713_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8716_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8716_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8716_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8716_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8716_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8716_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8717_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8717_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8717_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8717_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8717_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8717_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8718_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8718_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8718_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8718_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8718_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8718_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8720_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8720_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8720_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8720_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8720_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8720_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8724_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8724_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8724_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8724_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8724_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8724_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8725_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8725_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8725_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8725_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8725_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8725_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8727_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8727_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8727_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8727_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8727_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8727_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8729_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8729_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8729_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8729_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8729_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8729_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8731_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8731_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8731_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8731_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8731_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8731_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8732_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8732_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8732_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8732_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8732_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8732_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8736_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8736_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8736_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8736_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8736_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8736_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8737_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8737_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8737_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8737_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8737_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8737_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8742_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8742_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8742_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8742_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8742_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8742_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8743_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8743_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8743_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8743_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8743_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8743_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8745_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8745_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8745_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8745_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8745_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8745_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8746_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8746_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8746_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8746_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8746_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8746_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8747_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8747_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8747_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8747_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8747_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8747_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8749_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8749_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8749_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8749_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8749_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8749_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8751_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8751_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8751_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8751_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8751_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8751_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8755_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8755_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8755_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8755_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8755_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8755_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8761_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8761_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8761_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8761_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8761_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8761_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8762_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8762_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8762_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8762_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8762_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8762_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8767_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8767_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8767_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8767_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8767_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8767_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8768_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8768_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8768_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8768_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8768_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8768_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8772_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8772_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8772_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8772_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8772_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8772_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8774_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8774_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8774_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8774_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8774_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8774_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8776_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8776_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8776_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8776_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8776_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8776_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8777_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8777_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8777_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8777_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8777_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8777_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8780_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8780_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8780_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8780_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8780_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8780_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8782_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8782_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8782_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8782_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8782_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8782_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8784_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8784_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8784_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8784_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8784_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8784_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8787_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8787_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8787_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8787_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8787_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8787_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8788_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8788_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8788_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8788_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8788_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8788_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8789_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8789_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8789_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8789_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8789_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8789_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8790_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8790_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8790_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8790_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8790_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8790_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8795_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8795_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8795_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8795_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8795_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8795_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8797_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8797_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8797_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8797_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8797_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8797_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8800_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8800_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8800_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8800_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8800_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8800_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8801_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8801_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8801_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8801_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8801_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8801_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8805_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8805_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8805_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8805_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8805_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8805_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8806_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8806_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8806_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8806_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8806_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8806_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8809_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8809_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8809_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8809_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8809_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8809_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8813_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8813_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8813_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8813_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8813_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8813_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n<div id='gallery-5' class='gallery galleryid-39921 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-101-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-101-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-101-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-101-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-101-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-101-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-102-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-102-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-102-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-102-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-102-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-102-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-103-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-103-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-103-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-103-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-103-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-103-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-104-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-104-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-104-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-104-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-104-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-104-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-105-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-105-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-105-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-105-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-105-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-105-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-106-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-106-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-106-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-106-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-106-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-106-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-107-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-107-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-107-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-107-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-107-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-107-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-108-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-108-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-108-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-108-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-108-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-108-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-109-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-109-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-109-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-109-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-109-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-109-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-110-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-110-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-110-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-110-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-110-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-110-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-111-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-111-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-111-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-111-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-111-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-111-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-112-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-112-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-112-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-112-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-112-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-112-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-113-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-113-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-113-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-113-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-113-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-113-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-114-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-114-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-114-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-114-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-114-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-114-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-115-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-115-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-115-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-115-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-115-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-115-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-116-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-116-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-116-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-116-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-116-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-116-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-117-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-117-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-117-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-117-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-117-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-117-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-118-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-118-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-118-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-118-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-118-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-118-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-119-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-119-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-119-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-119-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-119-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-119-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-120-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-120-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-120-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-120-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-120-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-120-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-121-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-121-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-121-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-121-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-121-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-121-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-122-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-122-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-122-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-122-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-122-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-122-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-123-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-123-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-123-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-123-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-123-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-123-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-124-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-124-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-124-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-124-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-124-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-124-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-125-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-125-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-125-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-125-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-125-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-125-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-126-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-126-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-126-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-126-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-126-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-126-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-127-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-127-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-127-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-127-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-127-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-127-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-128-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-128-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-128-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-128-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-128-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-128-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-129-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-129-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-129-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-129-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-129-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-129-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-130-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-130-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-130-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-130-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-130-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-130-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-131-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-131-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-131-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-131-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-131-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-131-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-132-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-132-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-132-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-132-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-132-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-132-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-133-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-133-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-133-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-133-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-133-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-133-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-134-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-134-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-134-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-134-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-134-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-134-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-135-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-135-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-135-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-135-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-135-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-135-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-136-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-136-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-136-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-136-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-136-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-136-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-137-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-137-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-137-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-137-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-137-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-137-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-138-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-138-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-138-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-138-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-138-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-138-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-281-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-281-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-281-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-281-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-281-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-281-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-282-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-282-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-282-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-282-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-282-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-282-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-284-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-284-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-284-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-284-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-284-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-284-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-285-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-285-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-285-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-285-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-285-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-285-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-286-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-286-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-286-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-286-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-286-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-286-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-287-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-287-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-287-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-287-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-287-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-287-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-288-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-288-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-288-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-288-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-288-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-288-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-289-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-289-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-289-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-289-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-289-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-289-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-290-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-290-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-290-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-290-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-290-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-290-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-291-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-291-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-291-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-291-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-291-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-291-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-292-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-292-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-292-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-292-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-292-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-292-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-293-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-293-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-293-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-293-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-293-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-293-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-294-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-294-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-294-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-294-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-294-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-294-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-295-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-295-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-295-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-295-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-295-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-295-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-296-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-296-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-296-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-296-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-296-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-296-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-297-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-297-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-297-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-297-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-297-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-297-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-298-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-298-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-298-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-298-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-298-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-298-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-299-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-299-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-299-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-299-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-299-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-299-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-300-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-300-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-300-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-300-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-300-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-300-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-301-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-301-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-301-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-301-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-301-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-301-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-302-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-302-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-302-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-302-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-302-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-302-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-303-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-303-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-303-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-303-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-303-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-303-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-304-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-304-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-304-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-304-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-304-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-304-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-305-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-305-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-305-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-305-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-305-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-305-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-306-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-306-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-306-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-306-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-306-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-306-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-307-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-307-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-307-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-307-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-307-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-307-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-308-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-308-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-308-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-308-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-308-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-308-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-309-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-309-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-309-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-309-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-309-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-309-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-310-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-310-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-310-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-310-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-310-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-310-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-311-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-311-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-311-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-311-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-311-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-311-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-312-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-312-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-312-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-312-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-312-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-312-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-313-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-313-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-313-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-313-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-313-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-313-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-314-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-314-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-314-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-314-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-314-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-314-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-315-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-315-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-315-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-315-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-315-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-315-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-316-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-316-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-316-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-316-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-316-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-316-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-317-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-317-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-317-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-317-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-317-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-317-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-318-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-318-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-318-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-318-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-318-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-318-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-319-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-319-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-319-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-319-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-319-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-319-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-320-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-320-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-320-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-320-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-320-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-320-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-321-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-321-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-321-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-321-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-321-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-321-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-322-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-322-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-322-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-322-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-322-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-322-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n[\/vc_tab][vc_tab title=&#8221;L\u2019arrivo&#8221; tab_id=&#8221;1513087452147-3-10&#8243;]<div id='gallery-6' class='gallery galleryid-39921 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9058_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9058_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9058_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9058_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9058_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9058_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9057_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9057_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9057_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9057_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9057_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9057_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9056_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9056_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9056_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9056_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9056_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9056_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9052_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9052_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9052_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9052_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9052_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9052_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9051_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9051_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9051_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9051_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9051_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9051_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9049_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9049_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9049_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9049_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9049_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9049_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9048_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9048_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9048_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9048_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9048_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9048_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9047_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9047_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9047_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9047_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9047_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9047_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9045_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9045_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9045_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9045_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9045_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9045_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9044_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9044_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9044_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9044_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9044_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9044_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9042_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9042_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9042_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9042_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9042_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9042_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9040_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9040_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9040_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9040_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9040_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9040_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9038_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9038_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9038_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9038_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9038_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9038_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9035_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9035_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9035_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9035_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9035_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9035_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9033_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9033_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9033_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9033_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9033_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9033_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9031_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9031_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9031_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9031_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9031_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9031_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9029_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9029_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9029_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9029_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9029_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9029_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9027_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9027_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9027_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9027_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9027_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9027_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9025_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9025_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9025_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9025_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9025_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9025_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9023_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9023_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9023_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9023_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9023_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9023_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9021_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9021_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9021_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9021_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9021_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9021_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9019_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9019_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9019_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9019_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9019_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9019_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9017_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9017_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9017_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9017_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9017_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9017_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9015_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9015_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9015_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9015_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9015_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9015_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9014_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9014_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9014_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9014_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9014_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9014_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9012_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9012_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9012_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9012_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9012_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9012_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9010_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9010_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9010_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9010_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9010_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9010_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9007_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9007_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9007_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9007_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9007_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9007_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9003_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9003_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9003_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9003_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9003_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9003_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9002_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9002_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9002_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9002_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9002_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9002_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-9001_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9001_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9001_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9001_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9001_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-9001_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8999_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8999_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8999_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8999_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8999_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8999_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8997_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8997_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8997_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8997_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8997_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8997_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8995_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8995_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8995_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8995_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8995_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8995_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8993_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8993_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8993_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8993_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8993_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8993_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8991_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8991_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8991_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8991_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8991_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8991_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8989_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8989_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8989_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8989_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8989_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8989_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8985_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8985_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8985_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8985_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8985_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8985_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8983_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8983_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8983_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8983_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8983_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8983_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8981_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8981_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8981_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8981_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8981_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8981_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8977_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8977_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8977_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8977_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8977_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8977_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8975_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8975_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8975_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8975_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8975_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8975_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8973_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8973_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8973_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8973_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8973_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8973_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8969_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8969_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8969_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8969_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8969_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8969_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8967_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8967_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8967_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8967_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8967_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8967_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8965_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8965_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8965_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8965_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8965_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8965_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8963_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8963_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8963_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8963_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8963_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8963_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8961_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8961_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8961_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8961_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8961_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8961_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8960_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8960_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8960_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8960_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8960_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8960_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8957_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8957_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8957_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8957_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8957_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8957_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8956_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8956_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8956_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8956_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8956_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8956_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8954_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8954_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8954_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8954_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8954_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8954_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8953_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8953_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8953_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8953_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8953_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8953_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8951_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8951_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8951_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8951_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8951_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8951_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8948_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8948_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8948_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8948_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8948_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8948_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8946_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8946_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8946_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8946_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8946_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8946_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8944_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8944_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8944_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8944_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8944_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8944_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8942_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8942_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8942_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8942_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8942_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8942_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8941_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8941_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8941_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8941_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8941_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8941_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8938_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8938_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8938_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8938_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8938_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8938_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8935_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8935_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8935_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8935_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8935_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8935_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8932_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8932_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8932_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8932_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8932_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8932_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8926_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8926_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8926_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8926_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8926_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8926_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8924_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8924_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8924_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8924_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8924_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8924_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8921_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8921_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8921_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8921_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8921_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8921_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8918_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8918_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8918_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8918_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8918_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8918_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8916_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8916_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8916_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8916_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8916_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8916_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8913_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8913_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8913_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8913_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8913_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8913_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8911_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8911_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8911_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8911_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8911_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8911_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8908_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8908_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8908_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8908_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8908_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8908_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8903_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8903_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8903_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8903_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8903_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8903_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8901_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8901_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8901_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8901_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8901_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8901_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8897_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8897_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8897_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8897_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8897_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8897_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8894_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8894_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8894_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8894_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8894_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8894_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8891_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8891_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8891_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8891_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8891_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8891_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8889_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8889_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8889_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8889_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8889_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8889_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8885_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8885_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8885_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8885_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8885_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8885_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8883_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8883_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8883_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8883_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8883_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8883_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8882_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8882_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8882_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8882_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8882_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8882_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8881_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8881_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8881_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8881_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8881_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8881_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8877_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8877_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8877_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8877_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8877_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8877_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8874_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8874_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8874_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8874_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8874_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8874_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8871_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8871_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8871_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8871_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8871_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8871_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8870_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8870_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8870_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8870_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8870_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8870_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8866_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8866_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8866_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8866_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8866_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8866_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8865_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8865_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8865_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8865_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8865_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8865_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8863_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8863_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8863_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8863_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8863_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8863_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8861_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8861_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8861_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8861_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8861_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8861_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8858_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8858_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8858_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8858_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8858_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8858_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8856_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8856_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8856_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8856_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8856_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8856_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8853_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8853_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8853_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8853_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8853_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8853_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8849_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8849_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8849_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8849_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8849_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8849_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8845_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8845_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8845_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8845_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8845_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8845_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8840_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8840_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8840_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8840_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8840_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8840_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8835_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8835_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8835_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8835_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8835_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8835_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8830_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8830_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8830_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8830_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8830_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8830_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8829_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8829_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8829_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8829_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8829_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8829_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/www-giacomobrini-it-310-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8829_HQ-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8829_HQ-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8829_HQ-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8829_HQ-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8829_HQ-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8827_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8827_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8827_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8827_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8827_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8827_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/phgiacomobrini-2016_08_21-bikenight-udineugovizza-8824_lt-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8824_LT-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8824_LT-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8824_LT-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8824_LT-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/phGiacomoBrini-2016_08_21-BikeNight-UdineUgovizza-8824_LT-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n<div id='gallery-7' class='gallery galleryid-39921 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-230-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-230-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-230-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-230-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-230-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-230-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-229-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-229-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-229-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-229-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-229-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-229-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-228-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-228-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-228-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-228-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-228-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-228-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-227-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-227-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-227-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-227-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-227-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-227-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-225-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-225-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-225-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-225-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-225-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-225-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-224-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-224-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-224-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-224-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-224-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-224-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-222-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-222-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-222-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-222-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-222-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-222-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-220-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-220-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-220-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-220-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-220-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-220-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-219-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-219-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-219-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-219-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-219-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-219-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-217-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-217-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-217-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-217-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-217-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-217-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-216-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-216-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-216-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-216-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-216-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-216-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-215-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-215-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-215-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-215-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-215-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-215-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-214-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-214-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-214-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-214-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-214-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-214-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-211-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-211-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-211-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-211-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-211-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-211-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-210-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-210-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-210-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-210-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-210-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-210-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-209-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-209-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-209-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-209-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-209-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-209-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-208-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-208-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-208-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-208-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-208-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-208-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-206-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-206-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-206-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-206-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-206-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-206-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-204-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-204-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-204-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-204-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-204-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-204-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-203-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-203-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-203-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-203-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-203-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-203-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-201-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-201-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-201-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-201-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-201-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-201-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-200-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-200-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-200-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-200-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-200-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-200-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-198-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-198-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-198-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-198-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-198-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-198-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-195-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-195-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-195-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-195-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-195-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-195-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-194-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-194-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-194-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-194-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-194-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-194-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-192-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-192-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-192-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-192-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-192-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-192-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-191-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-191-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-191-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-191-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-191-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-191-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-190-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-190-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-190-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-190-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-190-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-190-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-188-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-188-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-188-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-188-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-188-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-188-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-185-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-185-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-185-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-185-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-185-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-185-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-183-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-183-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-183-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-183-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-183-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-183-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-182-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-182-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-182-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-182-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-182-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-182-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-180-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-180-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-180-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-180-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-180-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-180-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-178-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-178-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-178-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-178-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-178-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-178-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-176-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-176-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-176-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-176-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-176-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-176-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-175-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-175-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-175-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-175-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-175-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-175-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-174-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-174-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-174-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-174-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-174-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-174-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-173-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-173-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-173-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-173-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-173-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-173-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-172-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-172-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-172-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-172-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-172-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-172-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-170-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-170-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-170-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-170-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-170-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-170-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-169-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-169-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-169-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-169-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-169-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-169-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-167-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-167-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-167-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-167-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-167-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-167-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-166-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-166-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-166-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-166-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-166-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-166-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-165-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-165-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-165-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-165-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-165-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-165-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-164-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-164-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-164-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-164-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-164-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-164-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-163-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-163-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-163-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-163-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-163-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-163-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-161-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-161-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-161-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-161-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-161-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-161-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-160-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-160-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-160-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-160-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-160-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-160-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-159-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-159-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-159-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-159-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-159-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-159-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-158-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-158-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-158-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-158-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-158-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-158-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-157-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-157-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-157-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-157-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-157-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-157-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-155-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-155-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-155-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-155-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-155-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-155-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-154-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-154-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-154-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-154-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-154-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-154-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-152-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-152-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-152-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-152-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-152-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-152-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-151-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-151-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-151-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-151-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-151-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-151-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-149-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-149-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-149-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-149-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-149-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-149-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-147-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-147-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-147-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-147-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-147-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-147-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-145-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-145-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-145-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-145-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-145-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-145-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-144-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-144-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-144-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-144-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-144-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-144-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-143-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-143-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-143-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-143-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-143-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-143-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-142-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-142-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-142-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-142-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-142-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-142-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-139-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-139-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-139-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-139-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-139-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-139-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-388-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-388-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-388-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-388-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-388-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-388-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-387-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-387-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-387-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-387-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-387-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-387-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-385-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-385-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-385-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-385-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-385-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-385-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-383-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-383-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-383-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-383-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-383-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-383-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-382-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-382-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-382-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-382-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-382-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-382-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-381-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-381-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-381-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-381-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-381-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-381-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-380-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-380-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-380-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-380-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-380-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-380-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-378-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-378-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-378-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-378-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-378-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-378-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-377-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-377-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-377-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-377-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-377-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-377-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-376-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-376-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-376-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-376-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-376-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-376-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-375-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-375-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-375-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-375-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-375-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-375-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-374-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-374-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-374-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-374-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-374-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-374-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-373-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-373-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-373-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-373-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-373-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-373-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-372-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-372-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-372-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-372-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-372-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-372-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-371-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-371-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-371-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-371-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-371-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-371-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-367-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-367-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-367-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-367-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-367-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-367-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-366-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-366-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-366-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-366-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-366-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-366-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-365-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-365-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-365-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-365-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-365-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-365-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-364-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-364-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-364-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-364-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-364-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-364-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-363-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-363-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-363-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-363-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-363-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-363-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-362-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-362-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-362-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-362-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-362-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-362-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-361-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-361-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-361-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-361-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-361-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-361-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-360-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-360-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-360-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-360-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-360-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-360-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-359-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-359-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-359-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-359-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-359-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-359-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-358-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-358-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-358-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-358-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-358-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-358-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-357-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-357-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-357-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-357-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-357-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-357-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-356-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-356-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-356-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-356-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-356-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-356-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-355-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-355-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-355-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-355-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-355-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-355-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-354-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-354-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-354-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-354-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-354-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-354-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-353-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-353-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-353-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-353-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-353-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-353-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-352-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-352-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-352-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-352-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-352-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-352-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-351-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-351-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-351-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-351-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-351-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-351-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-350-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-350-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-350-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-350-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-350-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-350-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-349-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-349-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-349-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-349-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-349-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-349-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-348-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-348-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-348-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-348-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-348-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-348-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-347-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-347-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-347-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-347-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-347-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-347-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-346-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-346-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-346-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-346-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-346-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-346-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-345-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-345-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-345-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-345-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-345-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-345-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-344-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-344-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-344-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-344-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-344-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-344-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-340-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-340-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-340-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-340-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-340-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-340-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-339-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-339-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-339-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-339-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-339-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-339-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-338-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-338-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-338-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-338-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-338-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-338-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-336-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-336-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-336-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-336-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-336-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-336-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-335-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-335-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-335-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-335-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-335-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-335-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-334-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-334-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-334-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-334-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-334-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-334-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-333-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-333-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-333-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-333-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-333-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-333-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-332-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-332-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-332-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-332-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-332-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-332-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-331-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-331-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-331-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-331-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-331-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-331-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-330-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-330-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-330-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-330-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-330-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-330-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-328-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-328-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-328-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-328-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-328-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-328-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-327-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-327-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-327-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-327-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-327-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-327-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-326-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-326-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-326-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-326-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-326-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-326-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-324-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-324-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-324-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-324-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-324-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-324-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-active=\"1\" data-lbox=\"ilightbox_gallery-\" href='https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/udine-alpe-adria-2016-andrea-bighi-323-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-323-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" data-srcset=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-323-150x150.jpg 150w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-323-180x180.jpg 180w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-323-300x300.jpg 300w, https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/12\/Udine-Alpe-Adria-2016-Andrea-Bighi-323-600x600.jpg 600w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n[\/vc_tab][\/vc_tabs][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column width=&#8221;1\/1&#8243;][uncode_block id=&#8221;34935&#8243;][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;0&#8243; bottom_padding=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column width=&#8221;1\/1&#8243;][vc_separator sep_color=&#8221;color-785073&#8243;][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;2&#8243; bottom_padding=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column width=&#8221;1\/3&#8243;][vc_custom_heading separator=&#8221;yes&#8221; el_class=&#8221;bikenight-titoletto&#8221;]Notizie[\/vc_custom_heading][\/vc_column][vc_column width=&#8221;2\/3&#8243;][uncode_index el_id=&#8221;index-774645&#8243; index_type=&#8221;carousel&#8221; loop=&#8221;size:3|order_by:date|post_type:post|categories:38&#8243; carousel_lg=&#8221;3&#8243; carousel_md=&#8221;3&#8243; carousel_sm=&#8221;1&#8243; gutter_size=&#8221;3&#8243; post_items=&#8221;media|featured|onpost|original,title,sep-one|reduced&#8221; carousel_interval=&#8221;3000&#8243; carousel_navspeed=&#8221;400&#8243; stage_padding=&#8221;0&#8243; single_overlay_color=&#8221;color-121595&#8243; single_overlay_opacity=&#8221;50&#8243; single_padding=&#8221;2&#8243; el_class=&#8221;notizie&#8221;][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column width=&#8221;1\/1&#8243;][vc_separator sep_color=&#8221;color-785073&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row row_height_percent=&#8221;0&#8243; back_color=&#8221;color-121595&#8243; overlay_alpha=&#8221;50&#8243; equal_height=&#8221;yes&#8221; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; el_class=&#8221;bikenight-primariga&#8221;][vc_column column_width_percent=&#8221;100&#8243; style=&#8221;dark&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; medium_visibility=&#8221;yes&#8221; medium_width=&#8221;0&#8243; mobile_visibility=&#8221;yes&#8221; mobile_width=&#8221;0&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34061,"parent":34881,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-39921","page","type-page","status-publish","has-post-thumbnail","hentry","page_category-bike-night-en","page_category-edizioni-passate-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bike Night Udine - Alpe Adria 2016 - Witoor | Bike Night, Randonn\u00e9e Rando Imperator<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bike Night Udine - Alpe Adria 2016 - Witoor | Bike Night, Randonn\u00e9e Rando Imperator\" \/>\n<meta property=\"og:description\" content=\"[vc_row row_height_percent=&#8221;0&#8243; back_color=&#8221;color-121595&#8243; overlay_alpha=&#8221;50&#8243; equal_height=&#8221;yes&#8221; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; el_class=&#8221;bikenight-primariga&#8221;][vc_column column_width_percent=&#8221;100&#8243; style=&#8221;dark&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; medium_visibility=&#8221;yes&#8221; medium_width=&#8221;0&#8243; mobile_visibility=&#8221;yes&#8221; mobile_width=&#8221;0&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Witoor | Bike Night, Randonn\u00e9e Rando Imperator\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/witoor.bikenight\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-26T14:21:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/11\/bikenight-stampa-foto09.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@witoorbiketours\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/bike-night-alpeadria\\\/alpeadria-2016\\\/\",\"url\":\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/bike-night-alpeadria\\\/alpeadria-2016\\\/\",\"name\":\"Bike Night Udine - Alpe Adria 2016 - Witoor | Bike Night, Randonn\u00e9e Rando Imperator\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/witoor.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/bike-night-alpeadria\\\/alpeadria-2016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/bike-night-alpeadria\\\/alpeadria-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/witoor.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/bikenight-stampa-foto09.jpg\",\"datePublished\":\"2017-12-12T14:04:55+00:00\",\"dateModified\":\"2020-02-26T14:21:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/bike-night-alpeadria\\\/alpeadria-2016\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/bike-night-alpeadria\\\/alpeadria-2016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/bike-night-alpeadria\\\/alpeadria-2016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/witoor.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/bikenight-stampa-foto09.jpg\",\"contentUrl\":\"https:\\\/\\\/witoor.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/bikenight-stampa-foto09.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/bike-night-alpeadria\\\/alpeadria-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/witoor.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bike Night\",\"item\":\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bike Night Alpe Adria\",\"item\":\"https:\\\/\\\/witoor.com\\\/en\\\/bike-night\\\/bike-night-alpeadria\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Bike Night Udine &#8211; Alpe Adria 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/witoor.com\\\/#website\",\"url\":\"https:\\\/\\\/witoor.com\\\/\",\"name\":\"Witoor | Bike Night, Randonn\u00e9e Rando Imperator\",\"description\":\"Experience Real Cycling\",\"publisher\":{\"@id\":\"https:\\\/\\\/witoor.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/witoor.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/witoor.com\\\/#organization\",\"name\":\"Witoor\",\"url\":\"https:\\\/\\\/witoor.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/witoor.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/witoor.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/witoor-logo-viola.png\",\"contentUrl\":\"https:\\\/\\\/witoor.com\\\/web\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/witoor-logo-viola.png\",\"width\":700,\"height\":255,\"caption\":\"Witoor\"},\"image\":{\"@id\":\"https:\\\/\\\/witoor.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/witoor.bikenight\\\/\",\"https:\\\/\\\/x.com\\\/witoorbiketours\",\"http:\\\/\\\/instagram.com\\\/witoor\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bike Night Udine - Alpe Adria 2016 - Witoor | Bike Night, Randonn\u00e9e Rando Imperator","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/","og_locale":"en_US","og_type":"article","og_title":"Bike Night Udine - Alpe Adria 2016 - Witoor | Bike Night, Randonn\u00e9e Rando Imperator","og_description":"[vc_row row_height_percent=&#8221;0&#8243; back_color=&#8221;color-121595&#8243; overlay_alpha=&#8221;50&#8243; equal_height=&#8221;yes&#8221; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; el_class=&#8221;bikenight-primariga&#8221;][vc_column column_width_percent=&#8221;100&#8243; style=&#8221;dark&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; medium_visibility=&#8221;yes&#8221; medium_width=&#8221;0&#8243; mobile_visibility=&#8221;yes&#8221; mobile_width=&#8221;0&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; [&hellip;]","og_url":"https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/","og_site_name":"Witoor | Bike Night, Randonn\u00e9e Rando Imperator","article_publisher":"http:\/\/www.facebook.com\/witoor.bikenight\/","article_modified_time":"2020-02-26T14:21:43+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/11\/bikenight-stampa-foto09.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@witoorbiketours","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/","url":"https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/","name":"Bike Night Udine - Alpe Adria 2016 - Witoor | Bike Night, Randonn\u00e9e Rando Imperator","isPartOf":{"@id":"https:\/\/witoor.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/#primaryimage"},"image":{"@id":"https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/11\/bikenight-stampa-foto09.jpg","datePublished":"2017-12-12T14:04:55+00:00","dateModified":"2020-02-26T14:21:43+00:00","breadcrumb":{"@id":"https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/#primaryimage","url":"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/11\/bikenight-stampa-foto09.jpg","contentUrl":"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/11\/bikenight-stampa-foto09.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/alpeadria-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/witoor.com\/en\/"},{"@type":"ListItem","position":2,"name":"Bike Night","item":"https:\/\/witoor.com\/en\/bike-night\/"},{"@type":"ListItem","position":3,"name":"Bike Night Alpe Adria","item":"https:\/\/witoor.com\/en\/bike-night\/bike-night-alpeadria\/"},{"@type":"ListItem","position":4,"name":"Bike Night Udine &#8211; Alpe Adria 2016"}]},{"@type":"WebSite","@id":"https:\/\/witoor.com\/#website","url":"https:\/\/witoor.com\/","name":"Witoor | Bike Night, Randonn\u00e9e Rando Imperator","description":"Experience Real Cycling","publisher":{"@id":"https:\/\/witoor.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/witoor.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/witoor.com\/#organization","name":"Witoor","url":"https:\/\/witoor.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/witoor.com\/#\/schema\/logo\/image\/","url":"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/11\/witoor-logo-viola.png","contentUrl":"https:\/\/witoor.com\/web\/wp-content\/uploads\/2017\/11\/witoor-logo-viola.png","width":700,"height":255,"caption":"Witoor"},"image":{"@id":"https:\/\/witoor.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/witoor.bikenight\/","https:\/\/x.com\/witoorbiketours","http:\/\/instagram.com\/witoor"]}]}},"_links":{"self":[{"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/pages\/39921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/comments?post=39921"}],"version-history":[{"count":2,"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/pages\/39921\/revisions"}],"predecessor-version":[{"id":57127,"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/pages\/39921\/revisions\/57127"}],"up":[{"embeddable":true,"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/pages\/34881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/media\/34061"}],"wp:attachment":[{"href":"https:\/\/witoor.com\/en\/wp-json\/wp\/v2\/media?parent=39921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}